{"id":5270,"date":"2024-07-11T06:06:54","date_gmt":"2024-07-11T06:06:54","guid":{"rendered":"https:\/\/drmaslauskas.com\/about\/"},"modified":"2024-10-29T09:20:05","modified_gmt":"2024-10-29T09:20:05","slug":"about","status":"publish","type":"page","link":"https:\/\/drmaslauskas.com\/en\/about\/","title":{"rendered":"About"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-83494d77 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-eec09767\">\n<div class=\"wp-block-uagb-info-box uagb-block-3bcc7d51 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><span class=\"uagb-ifb-title-prefix\">ABOUT <\/span><h1 class=\"uagb-ifb-title\">Doctor of Plastic and Reconstructive Surgery, Doctor of Medicine<\/h1><\/div><p class=\"uagb-ifb-desc\">Plastic and reconstructive surgeon Med. M. Dr. K\u0119stutis Maslauskas is a <strong>plastic surgeon<\/strong> of the highest qualification, who has accumulated many years of experience in successfully implementing plastic surgery challenges in Lithuanian and foreign clinics.  <\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list uagb-block-085c02b6 uag-hide-mob\"><div class=\"uagb-icon-list__wrap\">\n<div class=\"wp-block-uagb-icon-list-child uagb-block-4045cc32\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path d=\"M384 48V512l-192-112L0 512V48C0 21.5 21.5 0 48 0h288C362.5 0 384 21.5 384 48z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\"><strong>1998:<\/strong> Graduated from Kaunas Medical University.<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-dfd569d9\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path d=\"M384 48V512l-192-112L0 512V48C0 21.5 21.5 0 48 0h288C362.5 0 384 21.5 384 48z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\"><strong>2003:<\/strong> Completed his residency in general surgery.<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-53b550d9\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path d=\"M384 48V512l-192-112L0 512V48C0 21.5 21.5 0 48 0h288C362.5 0 384 21.5 384 48z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\"><strong>2005:<\/strong> Completed his residency in plastic reconstructive surgery.<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-47f97ce9\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path d=\"M384 48V512l-192-112L0 512V48C0 21.5 21.5 0 48 0h288C362.5 0 384 21.5 384 48z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\"><strong>2005:<\/strong> Awarded the degree of Doctor of Medicine.<\/span><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list uagb-block-a6373acf uag-hide-desktop uag-hide-tab\"><div class=\"uagb-icon-list__wrap\">\n<div class=\"wp-block-uagb-icon-list-child uagb-block-89e3b5bb\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path d=\"M384 48V512l-192-112L0 512V48C0 21.5 21.5 0 48 0h288C362.5 0 384 21.5 384 48z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\"><strong>1998:<\/strong> Graduated from Kaunas Medical University.<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-7b4e3012\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path d=\"M384 48V512l-192-112L0 512V48C0 21.5 21.5 0 48 0h288C362.5 0 384 21.5 384 48z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\"><strong>2003:<\/strong> Completed his residency in general surgery.<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-28ee8c23\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path d=\"M384 48V512l-192-112L0 512V48C0 21.5 21.5 0 48 0h288C362.5 0 384 21.5 384 48z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\"><strong>2005:<\/strong> Completed his residency in plastic reconstructive surgery.<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-6de24a07\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path d=\"M384 48V512l-192-112L0 512V48C0 21.5 21.5 0 48 0h288C362.5 0 384 21.5 384 48z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\"><strong>2005:<\/strong> Awarded the degree of Doctor of Medicine.<\/span><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-bcb290f1\">\n<div class=\"wp-block-uagb-image uagb-block-5bdb9dae wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/07\/DSC_2935copy-2-831x1024.jpg ,https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/07\/DSC_2935copy-2-scaled.jpg 780w, https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/07\/DSC_2935copy-2-831x1024.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/07\/DSC_2935copy-2-831x1024.jpg\" alt=\"Maslauskas\" class=\"uag-image-1743\" width=\"408\" height=\"502\" title=\"\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uag-hide-mob uagb-block-48c4433d alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-48b87611\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-e3fc42bb\"><h2 class=\"uagb-heading-text\">Associations:<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list uagb-block-cee3bce6 uag-hide-mob\"><div class=\"uagb-icon-list__wrap\">\n<div class=\"wp-block-uagb-icon-list-child uagb-block-31eb108b\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M182.6 246.6C170.1 259.1 149.9 259.1 137.4 246.6L57.37 166.6C44.88 154.1 44.88 133.9 57.37 121.4C69.87 108.9 90.13 108.9 102.6 121.4L159.1 178.7L297.4 41.37C309.9 28.88 330.1 28.88 342.6 41.37C355.1 53.87 355.1 74.13 342.6 86.63L182.6 246.6zM182.6 470.6C170.1 483.1 149.9 483.1 137.4 470.6L9.372 342.6C-3.124 330.1-3.124 309.9 9.372 297.4C21.87 284.9 42.13 284.9 54.63 297.4L159.1 402.7L393.4 169.4C405.9 156.9 426.1 156.9 438.6 169.4C451.1 181.9 451.1 202.1 438.6 214.6L182.6 470.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">Lithuanian Plastic and reconstructive surgery society<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-6791f2d9\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M182.6 246.6C170.1 259.1 149.9 259.1 137.4 246.6L57.37 166.6C44.88 154.1 44.88 133.9 57.37 121.4C69.87 108.9 90.13 108.9 102.6 121.4L159.1 178.7L297.4 41.37C309.9 28.88 330.1 28.88 342.6 41.37C355.1 53.87 355.1 74.13 342.6 86.63L182.6 246.6zM182.6 470.6C170.1 483.1 149.9 483.1 137.4 470.6L9.372 342.6C-3.124 330.1-3.124 309.9 9.372 297.4C21.87 284.9 42.13 284.9 54.63 297.4L159.1 402.7L393.4 169.4C405.9 156.9 426.1 156.9 438.6 169.4C451.1 181.9 451.1 202.1 438.6 214.6L182.6 470.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">Member of the Rhinoplasty society of Europe<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-102cc8ff\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M182.6 246.6C170.1 259.1 149.9 259.1 137.4 246.6L57.37 166.6C44.88 154.1 44.88 133.9 57.37 121.4C69.87 108.9 90.13 108.9 102.6 121.4L159.1 178.7L297.4 41.37C309.9 28.88 330.1 28.88 342.6 41.37C355.1 53.87 355.1 74.13 342.6 86.63L182.6 246.6zM182.6 470.6C170.1 483.1 149.9 483.1 137.4 470.6L9.372 342.6C-3.124 330.1-3.124 309.9 9.372 297.4C21.87 284.9 42.13 284.9 54.63 297.4L159.1 402.7L393.4 169.4C405.9 156.9 426.1 156.9 438.6 169.4C451.1 181.9 451.1 202.1 438.6 214.6L182.6 470.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">Member of the International Society of Aesthetic Plastic Surgery (ISAPS)<\/span><\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uag-hide-desktop uag-hide-tab uagb-block-22f96dfe alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><\/div><\/div>\n\n<div class=\"wp-block-uagb-container uag-hide-desktop uag-hide-tab uagb-block-a79b1e46 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-5bea738f\"><h2 class=\"uagb-heading-text\">Associations:<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list uagb-block-4fefe354 uag-hide-desktop uag-hide-tab\"><div class=\"uagb-icon-list__wrap\">\n<div class=\"wp-block-uagb-icon-list-child uagb-block-4c0e62ed\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M182.6 246.6C170.1 259.1 149.9 259.1 137.4 246.6L57.37 166.6C44.88 154.1 44.88 133.9 57.37 121.4C69.87 108.9 90.13 108.9 102.6 121.4L159.1 178.7L297.4 41.37C309.9 28.88 330.1 28.88 342.6 41.37C355.1 53.87 355.1 74.13 342.6 86.63L182.6 246.6zM182.6 470.6C170.1 483.1 149.9 483.1 137.4 470.6L9.372 342.6C-3.124 330.1-3.124 309.9 9.372 297.4C21.87 284.9 42.13 284.9 54.63 297.4L159.1 402.7L393.4 169.4C405.9 156.9 426.1 156.9 438.6 169.4C451.1 181.9 451.1 202.1 438.6 214.6L182.6 470.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">Lithuanian Plastic and reconstructive surgery society<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-923d039c\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M182.6 246.6C170.1 259.1 149.9 259.1 137.4 246.6L57.37 166.6C44.88 154.1 44.88 133.9 57.37 121.4C69.87 108.9 90.13 108.9 102.6 121.4L159.1 178.7L297.4 41.37C309.9 28.88 330.1 28.88 342.6 41.37C355.1 53.87 355.1 74.13 342.6 86.63L182.6 246.6zM182.6 470.6C170.1 483.1 149.9 483.1 137.4 470.6L9.372 342.6C-3.124 330.1-3.124 309.9 9.372 297.4C21.87 284.9 42.13 284.9 54.63 297.4L159.1 402.7L393.4 169.4C405.9 156.9 426.1 156.9 438.6 169.4C451.1 181.9 451.1 202.1 438.6 214.6L182.6 470.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">Member of the Rhinoplasty society of Europe<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-c3b3b201\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M182.6 246.6C170.1 259.1 149.9 259.1 137.4 246.6L57.37 166.6C44.88 154.1 44.88 133.9 57.37 121.4C69.87 108.9 90.13 108.9 102.6 121.4L159.1 178.7L297.4 41.37C309.9 28.88 330.1 28.88 342.6 41.37C355.1 53.87 355.1 74.13 342.6 86.63L182.6 246.6zM182.6 470.6C170.1 483.1 149.9 483.1 137.4 470.6L9.372 342.6C-3.124 330.1-3.124 309.9 9.372 297.4C21.87 284.9 42.13 284.9 54.63 297.4L159.1 402.7L393.4 169.4C405.9 156.9 426.1 156.9 438.6 169.4C451.1 181.9 451.1 202.1 438.6 214.6L182.6 470.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">Member of the International Society of Aesthetic Plastic Surgery (ISAPS)<\/span><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-a573268f\"><h2 class=\"uagb-heading-text\">International experience:<\/h2><\/div>\n\n<div class=\"wp-block-uagb-content-timeline uagb-timeline__outer-wrap uagb-block-1350e29f uagb-timeline__content-wrap uagb-timeline__center-block  uagb-timeline__arrow-center uagb-timeline\">\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-91972997 uagb-timeline__right\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-right uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2023m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; Evolution Masterclass in Advanced Breast Surgery Techniques (Cyprus)<br\/>&#8211; ISAPS Olympiad Athens World Congress (Athens, Greece)<br\/>&#8211; &#8220;Breast Plastic and Reconstructive Surgery\u201d , Lithuanian Society of Plastic and Reconstructive Surgery (Klaip\u0117da, Lithuania)<br\/>&#8211; Polytech Lipofilling in reconstructive and aesthetic surgery conference (The Netherlands)<br\/>&#8211; Polytech Microthane &amp; Microthane B-lite live surgery masterclass&#8221; (Kaunas, Lithuania)<br\/>&#8211; Rhinoplasty conference &#8220;Rhinoplasty Full Circle Learning Experience&#8221; (Turkey, Istanbul)<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2023m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-bf58ad91 uagb-timeline__left\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-left uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2022m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; Rhinoplasty conference &#8220;Seventh Bergamo open rhinoplasty course&#8221;, Bergamo (Italy)<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2022m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-93167e15 uagb-timeline__right\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-right uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2021m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; Practical training &#8220;Allergan Peri- orbital treatment from A-Z&#8221;.<br\/>&#8211; Art and science in injectables for full-face. Deep dive in the anatomy and safe injections&#8221; Fillmed, Lithuania<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2021m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-b1360806 uagb-timeline__left\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-left uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2020m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; Facial contouring courses &#8220;MD Codes Immersion program Broadcast from London&#8221;, Allergan, Lithuania<br\/>&#8211; Body contouring courses &#8220;A day of science in fat grafting safety &amp; body contouring&#8221;<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2020m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-c8d3ecf2 uagb-timeline__right\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-right uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2019m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; Course &#8220;APTOS thread lifting methods&#8221;, Lithuania<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2019m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-39364855 uagb-timeline__left\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-left uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2018m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; MotivaHybrid Masterclass, Lithuania;<br\/>&#8211; Scientific practical conference &#8220;Hand and arm surgery news&#8221;, Lithuania;<br\/>&#8211; International scientific practical conference &#8220;Lithuanian Society of Plastic and Reconstructive Surgery Convention&#8221;, Lithuania;<br\/>&#8211; Member of the Lithuanian Plastic and reconstructive surgery society;<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2018m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-0e9fd069 uagb-timeline__right\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-right uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2017m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; Conference &#8220;Hand Surgery and Plastic Surgery&#8221;, Lithuania;<br\/>&#8211; Course &#8220;Breast Enhancement&#8221;, Spain;<br\/>&#8211; Scientific and Practical Conference &#8220;Breast Aesthetics Masterclass&#8221;, Sweden;<br\/>&#8211; Training &#8220;Silhouette Soft hands-on training&#8221;, Lithuania;<br\/>Conference &#8220;Complications in Plastic Surgery&#8221;, Lithuania;<br\/>&#8211; Continuing Scientific Practical Conference &#8220;Treatment and Diagnostic Innovations in Surgery&#8221;, Lithuania;<br\/>&#8211; Conference &#8220;Modern Cosmetic Surgery: Breast Implants and Facial Injections&#8221;, Lithuania<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2017m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-c185de93 uagb-timeline__left\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-left uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2016m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; Training &#8220;Advanced Use of Microthane Breast Implants&#8221;, Lithuania;<br\/>&#8211; ISAPS XXIIIrd Congress, Japan;<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2016m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-111489a4 uagb-timeline__right\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-right uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2015m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; Surgical Excellence Mentoring Course, The Netherlands;<br\/>&#8211; Annual ASAPS Conference, Australia;<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2015m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-41906dc2 uagb-timeline__left\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-left uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2014m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; Course &#8220;Periorbital treatment&#8221;, Lithuania;<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2014m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-7b2b1f68 uagb-timeline__right\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-right uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2013m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; 3rd International ISAPS Workshop, Russia;<br\/>&#8211; Participant of the 17th IPRAS World Congress;<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2013m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-02342203 uagb-timeline__left\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-left uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2012m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; 2-day Allergan Masterclass, Germany;<br\/>&#8211; 3rd Bergan Rhinoplasty Open Course from Beginner to Advanced Level, Italy;<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2012m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-5dc4be7f uagb-timeline__right\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-right uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2011m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; Participated in the educational programme &#8220;News of Facial Aesthetics&#8221;, Lithuania;<br\/>&#8211; Obtained IPRAS membership certificate;<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2011m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-070417ce uagb-timeline__left\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-left uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2010m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; Training course &#8220;Laser Lipolysis and Laser Liposuction&#8221;, Lithuania;<br\/>&#8211; Theoretical and practical training on GENETHIA products, Lithuania;<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2010m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-6bad12ac uagb-timeline__right\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-right uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2008m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; Scientific Practical Conference &#8220;Reconstructive Breast and Torso Surgery&#8221;, Lithuania;<br\/>&#8211; 5th International Plastic Surgery Course &#8220;Facial Rejuvenation and Body Contouring: abdominoplasty, breast reduction, body lift, liposuction and lipofilling&#8221;, Russia;<br\/>&#8211; Plastic Surgery Specialist qualification, Sweden;<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2008m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-60963bf6 uagb-timeline__left\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-left uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2005m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; Thesis &#8220;Effectiveness of Active Surgical Tactics in the Treatment of Deep Partial-thickness Burns of the Hands and Wrists&#8221; in the field of biomedical sciences, Kaunas Medical University;<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2005m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-5689fcc5 uagb-timeline__right\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-right uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2004m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; Ghent University Hospital, Belgium;<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2004m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-082beb31 uagb-timeline__left\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-left uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2003m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; Scientific and practical conference &#8220;Breast Cancer. Plastic Reconstructive Surgery&#8221;, Lithuania;<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2003m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-7a7e6741 uagb-timeline__right\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-right uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">2000m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; University Hospital of Oviedo, Spain;<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">2000m.<\/div><\/article>\n\n\n\n<article class=\"wp-block-uagb-content-timeline-child uagb-timeline__field uagb-timeline-child-3689296a uagb-timeline__left\"><div class=\"uagb-timeline__marker out-view-uagb-timeline__icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M160 32V64H288V32C288 14.33 302.3 0 320 0C337.7 0 352 14.33 352 32V64H400C426.5 64 448 85.49 448 112V160H0V112C0 85.49 21.49 64 48 64H96V32C96 14.33 110.3 0 128 0C145.7 0 160 14.33 160 32zM0 192H448V464C448 490.5 426.5 512 400 512H48C21.49 512 0 490.5 0 464V192zM64 304C64 312.8 71.16 320 80 320H112C120.8 320 128 312.8 128 304V272C128 263.2 120.8 256 112 256H80C71.16 256 64 263.2 64 272V304zM192 304C192 312.8 199.2 320 208 320H240C248.8 320 256 312.8 256 304V272C256 263.2 248.8 256 240 256H208C199.2 256 192 263.2 192 272V304zM336 256C327.2 256 320 263.2 320 272V304C320 312.8 327.2 320 336 320H368C376.8 320 384 312.8 384 304V272C384 263.2 376.8 256 368 256H336zM64 432C64 440.8 71.16 448 80 448H112C120.8 448 128 440.8 128 432V400C128 391.2 120.8 384 112 384H80C71.16 384 64 391.2 64 400V432zM208 384C199.2 384 192 391.2 192 400V432C192 440.8 199.2 448 208 448H240C248.8 448 256 440.8 256 432V400C256 391.2 248.8 384 240 384H208zM320 432C320 440.8 327.2 448 336 448H368C376.8 448 384 440.8 384 432V400C384 391.2 376.8 384 368 384H336C327.2 384 320 391.2 320 400V432z\"><\/path><\/svg><\/div><div class=\"uagb-timeline__day-new uagb-timeline__day-left uagb-timeline__events-inner-new\"><div class=\"uagb-timeline__events-inner--content\"><div class=\"uagb-timeline__date-hide uagb-timeline__inner-date-new\">1998m.<\/div><h4 class=\"uagb-timeline__heading\"><\/h4><p class=\"uagb-timeline-desc-content\">&#8211; Bursa University Hospital, Turkey.<\/p><div class=\"uagb-timeline__arrow\"><\/div><\/div><\/div><div class=\"uagb-timeline__date-new\">1998m.<\/div><\/article>\n<div class=\"uagb-timeline__line\"><div class=\"uagb-timeline__line__inner\"><\/div><\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-d7f896d3 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Associations: Associations: International experience:<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-5270","page","type-page","status-publish","hentry"],"spectra_custom_meta":{"adv-header-id-meta":[""],"stick-header-meta":[""],"theme-transparent-header-meta":[""],"ast-site-content-layout":["default"],"_last_translation_edit_mode":["native-editor"],"_edit_lock":["1730193836:2"],"_uag_custom_page_level_css":[""],"astra-migrate-meta-layouts":["set"],"_themeisle_gutenberg_block_has_review":[""],"footnotes":[""],"_edit_last":["2"],"_wpml_media_has_media":["1"],"_wp_page_template":[""],"_uag_css_file_name":["uag-css-5270.css"],"_uag_js_file_name":["uag-js-5270.js"],"rank_math_title":["Dr. K\u0119stutis Maslauskas: Facial Plastic Surgery"],"rank_math_description":["Dr. K\u0119stutis Maslauskas - a plastic and reconstructive surgeon. Procedures in Vilnius and Kaunas, consultations in London and Dublin."],"rank_math_focus_keyword":["K\u0119stutis Maslauskas"],"rank_math_news_sitemap_robots":["index"],"rank_math_robots":["a:1:{i:0;s:5:\"index\";}"],"rank_math_seo_score":["55"],"rank_math_og_content_image":["a:2:{s:5:\"check\";s:32:\"88bc4dc57617fd340cd9cdb41e7e4e76\";s:6:\"images\";a:1:{i:0;s:79:\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/07\/DSC_2935copy-2-831x1024.jpg\";}}"],"rank_math_internal_links_processed":["1"],"_uag_page_assets":["a:9:{s:3:\"css\";s:191101:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all .2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.uagb-timeline__outer-wrap{position:relative}.uagb-timeline__outer-wrap .uagb-timeline__field{position:relative;display:flex;align-items:flex-start;margin-bottom:inherit;color:inherit;font-size:inherit}.uagb-timeline__outer-wrap .uagb-timeline__field:not(:last-child){margin-bottom:20px}.uagb-timeline__outer-wrap .uagb-timeline__field a{margin-bottom:inherit;text-decoration:none}.uagb-timeline__outer-wrap .uagb-timeline__field a.uagb-timeline__image{position:relative;display:block;max-width:100%}.uagb-timeline__outer-wrap .uagb-timeline__field a.uagb-timeline__image img{display:inline-block;box-sizing:content-box;height:auto;max-width:100%}.uagb-timeline__outer-wrap .uagb-timeline__field .uagb-timeline__author-link{text-transform:capitalize}.uagb-timeline__outer-wrap .uagb-timeline__field a.uagb-timeline__link{display:inline-block}.uagb-timeline__outer-wrap .uagb-timeline__field.uagb-timeline__left.hide-events .uagb-timeline__events-inner-new,.uagb-timeline__outer-wrap .uagb-timeline__field.uagb-timeline__left.hide-events .uagb-timeline__date-new{visibility:hidden}.uagb-timeline__outer-wrap .uagb-timeline__field.uagb-timeline__right.hide-events .uagb-timeline__events-inner-new,.uagb-timeline__outer-wrap .uagb-timeline__field.uagb-timeline__right.hide-events .uagb-timeline__date-new{visibility:hidden}.uagb-timeline__outer-wrap .uagb-timeline__field .uagb-timeline__image a{position:relative;display:block;max-width:100%}.uagb-timeline__outer-wrap .uagb-timeline__field .uagb-timeline__image img{display:inline-block;box-sizing:content-box}.uagb-timeline__outer-wrap .uagb-timeline__line{position:absolute;transform:translateX(-50%);-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);width:3px;background-color:#eee}.uagb-timeline__outer-wrap .uagb-timeline__line .uagb-timeline__line__inner{width:100%;background-color:#0693e3}.uagb-timeline__outer-wrap svg{display:inline-block;vertical-align:middle;font-size:16px;font-style:normal;line-height:16px}.uagb-timeline__outer-wrap .uagb-timeline__field:hover .uagb-timeline__marker{transition:all .2s ease-in-out}.uagb-timeline__outer-wrap .uagb-timeline__marker{position:relative;display:flex;z-index:1;justify-content:center;align-items:center;min-width:3em;min-height:3em;background-color:#eee;border-radius:999px;line-height:48px;transition:all .2s ease-in-out}.uagb-timeline__outer-wrap .uagb-timeline__year{position:relative;display:flex}.uagb-timeline__outer-wrap .uagb-timeline__year span{display:inline-block;padding-bottom:6px}.uagb-timeline__outer-wrap.uagb-timeline__arrow-center .uagb-timeline__field{align-items:center}.uagb-timeline__outer-wrap.uagb-timeline__arrow-center .uagb-timeline__left .uagb-timeline__arrow,.uagb-timeline__outer-wrap.uagb-timeline__arrow-center .uagb-timeline__right .uagb-timeline__arrow{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__outer-wrap.uagb-timeline__arrow-bottom .uagb-timeline__field{align-items:flex-end}.uagb-timeline__outer-wrap.uagb-timeline__arrow-bottom .uagb-timeline__left .uagb-timeline__arrow,.uagb-timeline__outer-wrap.uagb-timeline__arrow-bottom .uagb-timeline__right .uagb-timeline__arrow{top:100%;transform:translateY(-100%)}.uagb-timeline__outer-wrap.uagb-timeline__arrow-bottom .uagb-timeline__date-new .uagb-timeline__date-new{padding-top:8px;padding-bottom:8px}.uagb-timeline__outer-wrap .uagb-timeline__date .uagb-timeline__inner-date-new{margin:0;white-space:nowrap}.uagb-timeline__outer-wrap .in-view i.uagb-timeline__in-view-icon{-webkit-transition:background .25s ease-out .25s,width .25s ease-in-out,height .25s ease-in-out,color .25s ease-in-out,font-size .25s ease-in-out;-webkit-transition:background .25s ease-out .25s,width .25s ease-in-out,height .25s ease-in-out,color .25s ease-in-out,font-size .25s ease-out;transition:background .25s ease-out .25s,width .25s ease-in-out,height .25s ease-in-out,color .25s ease-in-out,font-size .25s ease-out}.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__date-new{display:none}.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__date-new{display:none}.uagb-timeline__outer-wrap p:empty{display:none}.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__line{position:absolute;transform:translateX(50%);-webkit-transform:translateX(50%);-ms-transform:translateX(50%)}.uagb-timeline__outer-wrap span.dashicons-admin-users.dashicons{display:inline;vertical-align:baseline;margin-right:4px}.uagb-content{word-break:break-word}.uagb-timeline__headingh1,.uagb-timeline__headingh2,.uagb-timeline__headingh3,.uagb-timeline__headingh4,.uagb-timeline__headingh5,.uagb-timeline__headingh6{margin-bottom:0}.uagb-timeline__inner-date-new p,.uagb-timeline__date-inner .uagb-timeline__inner-date-new p{margin-bottom:0}.uagb-timeline__center-block{text-align:center}.uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;top:50%;right:0;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);border-left:13px solid #eee;transform:translateY(-50%);content:\"\";-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block .uagb-timeline__marker{flex-grow:0;flex-shrink:0;order:1}.uagb-timeline__center-block .uagb-timeline__date-hide{display:none}.uagb-timeline__center-block .uagb-timeline__field.uagb-timeline__right{flex-direction:row-reverse}.uagb-timeline__center-block .uagb-timeline__day-new,.uagb-timeline__center-block .uagb-timeline__date-new{display:block;position:relative;flex-grow:1;flex-basis:50%;max-width:100%}.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-new{order:2}.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__date-new{display:flex;justify-content:flex-start}.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow{position:absolute;top:0;right:-10px;width:10px;height:40px}.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__day-new{order:2}.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__date-new{display:flex;justify-content:flex-end}.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow{position:absolute;top:0;left:-10px;width:10px;height:40px}.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block .uagb-timeline__line{right:auto;left:50%}.uagb-timeline__right-block .uagb-timeline__field{flex-direction:row-reverse}.uagb-timeline__right-block .uagb-timeline__date-new{display:flex;align-items:center;margin-left:10px}.uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:inherit}.uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__events-inner-new,.uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__events-inner-new{text-align:right}.uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%)}.uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__arrow{position:absolute;top:0;right:0;width:10px;height:40px}.uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow{right:-12px}.uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__arrow{right:-10px}.uagb-timeline__right-block .uagb-timeline__marker,.uagb-timeline__right-block .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__right-block .uagb-timeline__day-new{flex-grow:1;margin-right:14px}.uagb-timeline__right-block .uagb-timeline__marker{flex-grow:0;flex-shrink:0}.uagb-timeline__left-block{text-align:left}.uagb-timeline__left-block .uagb-timeline__marker,.uagb-timeline__left-block .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__left-block .uagb-timeline__line{inset-inline-start:20px;inset-inline-end:auto}.uagb-timeline__left-block .uagb-timeline__day-new{flex-grow:1;order:1;margin-left:14px}.uagb-timeline__left-block .uagb-timeline__date-new{margin-right:10px}.uagb-timeline__left-block .uagb-timeline__marker{flex-grow:0;flex-shrink:0;order:0}.uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__events-inner-new,.uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__events-inner-new{text-align:left}.uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%)}.uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow{position:absolute;top:0;width:10px;height:40px}.uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__arrow{left:-10px}.uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow{left:-12px}.uagb-timeline__left-block .uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-right:13px solid #eee;border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__day-right .uagb-timeline__events-inner{text-align:right}.uagb-timeline__day-left .uagb-timeline__events-inner{text-align:left}.uagb-timeline__arrow-top .uagb-timeline__date-new .uagb-timeline__date-new{padding-top:8px;padding-bottom:8px}.uagb-timeline__events-inner-new,.uagb-timeline__arrow{transition:background .2s ease-in-out}.uagb-timeline__arrow::after{transition:border-color .2s ease-in-out}.uagb-timeline__date-new{transition:color .2s ease-in-out}.uagb-timeline__day-left .uagb-timeline__arrow::after{position:absolute;left:0;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__right .uagb-timeline__day-left .uagb-timeline__arrow::after{right:0}.uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;right:0;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__icon{position:relative;z-index:1;vertical-align:middle;width:100px;height:100px;border-radius:50%;text-align:center;line-height:100px;-webkit-border-radius:50%}.uagb-timeline__left{text-align:left}.uagb-timeline__right{text-align:right}.uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__arrow::after{border-left:13px solid #eee}.uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__arrow::after{border-left:13px solid #eee}.uagb-timeline__center-block .uagb-timeline__day-left .uagb-timeline__arrow::after{border-right:13px solid #eee}.uagb-timeline__left-block .uagb-timeline__day-left .uagb-timeline__arrow::after{border-right:13px solid #eee}.uagb-timeline__day-right .uagb-timeline__events-inner-new{border-radius:4px 4px 4px 4px}.uagb-timeline__day-left .uagb-timeline__events-inner-new{border-radius:4px 4px 4px 4px}.uagb-timeline__arrow{height:3em}.uagb-timeline__right-block .uagb-timeline__line{inset-inline-end:1.5em}@media screen and (max-width: 1023px){.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__line{position:absolute;right:16px;left:auto;transform:translateX(50%);-webkit-transform:translateX(50%);-ms-transform:translateX(50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-hide{display:block}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__line{right:auto;left:20px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__marker{-webkit-box-ordinal-group:1;-webkit-order:0;-moz-box-ordinal-group:1;-ms-flex-order:0;flex-grow:0;flex-shrink:0;order:0;-webkit-flex-shrink:0;-ms-flex-negative:0;-webkit-box-flex:0;-webkit-flex-grow:0;-moz-box-flex:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new{flex-grow:1;order:1;margin-left:16px;-webkit-box-flex:1;-webkit-flex-grow:1;-moz-box-flex:1;-ms-flex-positive:1;-webkit-box-ordinal-group:2;-webkit-order:1;-moz-box-ordinal-group:2;-ms-flex-order:1}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow{position:absolute;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow{left:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow{left:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__field.uagb-timeline__right{-webkit-box-orient:unset;-webkit-box-direction:unset;-webkit-flex-direction:unset;-moz-box-orient:unset;-moz-box-direction:unset;-ms-flex-direction:unset;flex-direction:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-new{-webkit-box-flex:unset;-webkit-flex-grow:unset;-moz-box-flex:unset;-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;width:100%;max-width:100%;-webkit-flex-basis:unset;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__field{-webkit-box-orient:horizontal;-webkit-box-direction:reverse;-webkit-flex-direction:row-reverse;-moz-box-orient:horizontal;-moz-box-direction:reverse;-ms-flex-direction:row-reverse;flex-direction:row-reverse}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{position:absolute;right:0;left:auto;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow{right:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{right:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__marker{-webkit-flex-shrink:0;-ms-flex-negative:0;flex-grow:0;flex-shrink:0;-webkit-box-flex:0;-webkit-flex-grow:0;-moz-box-flex:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new{flex-grow:1;margin-right:16px;-webkit-box-flex:1;-webkit-flex-grow:1;-moz-box-flex:1;-ms-flex-positive:1}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__date-new{-webkit-box-flex:unset;-webkit-flex-grow:unset;-moz-box-flex:unset;-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;max-width:100%;-webkit-flex-basis:unset;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__date-new{display:none}}@media screen and (max-width: 767px){.uagb-timeline-responsive-none .uagb-timeline__events-inner-new{padding:15px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__date-hide{display:block}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__line{right:auto;left:20px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__marker{-webkit-box-ordinal-group:1;-webkit-order:0;-moz-box-ordinal-group:1;-ms-flex-order:0;flex-grow:0;flex-shrink:0;order:0;-webkit-flex-shrink:0;-ms-flex-negative:0;-webkit-box-flex:0;-webkit-flex-grow:0;-moz-box-flex:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-new{flex-grow:1;order:1;margin-left:16px;-webkit-box-flex:1;-webkit-flex-grow:1;-moz-box-flex:1;-ms-flex-positive:1;-webkit-box-ordinal-group:2;-webkit-order:1;-moz-box-ordinal-group:2;-ms-flex-order:1}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__arrow{position:absolute;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__arrow{left:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__arrow{left:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__day-left .uagb-timeline__events-inner-new{text-align:left}.uagb-timeline__left-block .uagb-timeline__date-new{margin-right:10px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__field.uagb-timeline__right{-webkit-box-orient:unset;-webkit-box-direction:unset;-webkit-flex-direction:unset;-moz-box-orient:unset;-moz-box-direction:unset;-ms-flex-direction:unset;flex-direction:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__date-new{-webkit-box-flex:unset;-webkit-flex-grow:unset;-moz-box-flex:unset;-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;max-width:100%;-webkit-flex-basis:unset;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__field{-webkit-box-orient:horizontal;-webkit-box-direction:reverse;-webkit-flex-direction:row-reverse;-moz-box-orient:horizontal;-moz-box-direction:reverse;-ms-flex-direction:row-reverse;flex-direction:row-reverse}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{position:absolute;right:0;left:auto;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow{right:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{right:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__marker{-webkit-flex-shrink:0;-ms-flex-negative:0;flex-grow:0;flex-shrink:0;-webkit-box-flex:0;-webkit-flex-grow:0;-moz-box-flex:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-new{flex-grow:1;margin-right:16px;-webkit-box-flex:1;-webkit-flex-grow:1;-moz-box-flex:1;-ms-flex-positive:1}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__line{position:absolute;right:16px;left:auto;transform:translateX(50%);-webkit-transform:translateX(50%);-ms-transform:translateX(50%)}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__date-new{-webkit-box-flex:unset;-webkit-flex-grow:unset;-moz-box-flex:unset;-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;max-width:100%;-webkit-flex-basis:unset;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__day-new{-webkit-box-ordinal-group:unset;-webkit-order:unset;-moz-box-ordinal-group:unset;-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-left .uagb-timeline__arrow::after,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__arrow::after,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__arrow::after{border-right:13px solid #eee;border-left:none}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-right .uagb-timeline__arrow::after,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-left .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__arrow::after{border-right:none;border-left:13px solid #eee}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__line,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__line{right:auto;left:17.5px}.uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__line,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__line{right:17.5px;left:auto}.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__author-link,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__link_parent,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__link,.uagb-timeline__responsive-mobile.uagb-timeline__center-block a.uagb-timeline__image,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__image a,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__heading,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline-desc-content,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__date-inner,.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__inner-date-new{text-align:left}.uagb-timeline__responsive-mobile.uagb-timeline__center-block .uagb-timeline__date-hide.uagb-timeline__date-inner{text-align:left}}@media(max-width: 976px){.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__line{position:absolute;right:16px;left:auto;transform:translateX(50%);-webkit-transform:translateX(50%);-ms-transform:translateX(50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-hide{display:block}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__line{right:auto;left:17.5px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__marker{-ms-flex-order:0;flex-grow:0;flex-shrink:0;order:0;-ms-flex-negative:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new{flex-grow:1;order:1;margin-left:16px;-ms-flex-positive:1;-ms-flex-order:1}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow{position:absolute;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow{left:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow{left:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right{text-align:left}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__arrow::after{position:absolute;display:inline;width:0;height:0;border-top:12px solid rgba(0,0,0,0);border-bottom:12px solid rgba(0,0,0,0);content:\"\"}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__field.uagb-timeline__right{-ms-flex-direction:unset;flex-direction:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__date-new{-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;width:100%;max-width:100%;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__day-new{-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__day-new{-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__field{-ms-flex-direction:row-reverse;flex-direction:row-reverse}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__events-inner-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__events-inner-new{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{position:absolute;right:0;left:auto;width:10px;height:40px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow{right:-12px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{right:-10px}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__marker,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new{position:relative;max-width:100%}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__marker{-ms-flex-negative:0;flex-grow:0;flex-shrink:0;-ms-flex-positive:0}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new{flex-grow:1;margin-right:16px;-ms-flex-positive:1}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow::after{top:50%;transform:translateY(-50%);-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%)}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right{text-align:right}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__date-new{-ms-flex-positive:unset;position:relative;flex-grow:unset;flex-basis:unset;max-width:100%;-ms-flex-preferred-size:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__day-new{-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__day-new{-ms-flex-order:unset;order:unset}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__date-new,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__date-new{display:none}.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__arrow::after,.uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-left .uagb-timeline__arrow::after{border-right:13px solid #eee;border-left:none}.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__author-link,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__link_parent,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__link,.uagb-timeline__responsive-tablet.uagb-timeline__center-block a.uagb-timeline__image,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__image a,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__heading,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline-desc-content,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__date-inner,.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__inner-date-new{text-align:left}.uagb-timeline__responsive-tablet.uagb-timeline__center-block .uagb-timeline__date-hide.uagb-timeline__date-inner{text-align:left}}.wp-block-uagb-content-timeline .wp-block-uagb-content-timeline-child .uagb-timeline__events-inner--content .uagb-timeline__heading{margin-top:unset}.wp-block-uagb-content-timeline .wp-block-uagb-content-timeline-child .uagb-timeline__events-inner--content p.uagb-timeline-desc-content{margin-bottom:unset}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap .uagb-timeline__field{display:unset}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap .uagb-timeline__field .uagb-timeline__widget{position:relative;display:flex;align-items:flex-start;font-size:inherit;color:inherit;margin-bottom:inherit}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__left-block .uagb-timeline__date-new{display:none}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__right-block .uagb-timeline__date-new{display:none}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__widget.uagb-timeline__right{flex-direction:row-reverse}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__marker{order:1;flex-shrink:0;flex-grow:0}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-new{order:2;padding-left:0;padding-right:12px}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__day-new{order:2;padding-right:0;padding-left:12px}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow{right:0;top:0;width:10px;height:40px;position:absolute}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow{left:0;top:0;width:10px;height:40px;position:absolute}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__right-block .uagb-timeline__widget{flex-direction:row-reverse}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__arrow-center .uagb-timeline__widget{align-items:center}.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__arrow-center .uagb-timeline__left .uagb-timeline__arrow,.wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__arrow-center .uagb-timeline__right .uagb-timeline__arrow{top:50%;-webkit-transform:translateY(-50%);-ms-transform:translateY(-50%);transform:translateY(-50%)}.wp-block-uagb-post-timeline .uagb-timeline__link_parent .uagb-timeline__link.wp-block-button__link{width:auto}.rtl .uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow{right:auto;left:-10px}.rtl .uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow{left:auto;right:-10px}.rtl .uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow::after{right:auto;left:0;border-left:none;border-right:13px solid #eee}.rtl .uagb-timeline__center-block .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block .uagb-timeline__day-left .uagb-timeline__arrow::after{left:auto;right:0;border-right:none;border-left:13px solid #eee}.rtl .uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-left .uagb-timeline__arrow::after{right:auto;left:0}.rtl .uagb-timeline__left-block .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__day-new{margin-left:0;margin-right:14px}.rtl .uagb-timeline__left-block .uagb-timeline__date-new,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__date-new{margin-right:0;margin-left:10px}.rtl .uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__events-inner-new,.rtl .uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__events-inner-new,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__events-inner-new,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__events-inner-new{text-align:right}.rtl .uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__right .uagb-timeline__arrow{left:auto;right:-10px}.rtl .uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow{left:auto;right:-12px}.rtl .uagb-timeline__left-block .uagb-timeline__day-right .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__day-right .uagb-timeline__arrow::after{right:auto;left:0;border-right:none;border-left:13px solid #eee}.rtl .uagb-timeline__left-block .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__day-left .uagb-timeline__arrow::after{left:auto;right:0;border-right:none;border-left:13px solid #eee}.rtl .uagb-timeline__right-block .uagb-timeline__date-new,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__date-new{margin-left:0;margin-right:10px}.rtl .uagb-timeline__right-block .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__day-new{margin-right:0;margin-left:14px}.rtl .uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__events-inner-new,.rtl .uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__events-inner-new,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__events-inner-new,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__events-inner-new{text-align:left}.rtl .uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow{right:auto;left:-12px}.rtl .uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__left .uagb-timeline__arrow{right:auto;left:-10px}.rtl .uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__arrow::after{right:auto;left:0;border-left:none;border-right:13px solid #eee}.rtl .uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__arrow::after{left:auto;right:0;border-left:none;border-right:13px solid #eee}.rtl .uagb-timeline__day-right .uagb-timeline__events-inner,[dir=rtl] .uagb-timeline__day-right .uagb-timeline__events-inner{text-align:left}.rtl .uagb-timeline__day-left .uagb-timeline__events-inner,[dir=rtl] .uagb-timeline__day-left .uagb-timeline__events-inner{text-align:right}.rtl .uagb-timeline__left,[dir=rtl] .uagb-timeline__left{text-align:right}.rtl .uagb-timeline__right,[dir=rtl] .uagb-timeline__right{text-align:left}.rtl .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-new,[dir=rtl] .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__day-new{padding-left:12px;padding-right:0}.rtl .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__day-new,[dir=rtl] .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__day-new{padding-right:12px;padding-left:0}.rtl .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow{right:auto;left:0}.rtl .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .wp-block-uagb-content-timeline .uagb-timeline__content-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow{left:auto;right:0}@media screen and (max-width: 1023px){.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-new{margin-left:0;margin-right:16px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__line,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__line{left:auto;right:20px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__right .uagb-timeline__arrow{left:auto;right:-10px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__left .uagb-timeline__arrow{left:auto;right:-12px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__arrow::after,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-right .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline__day-left .uagb-timeline__arrow::after{right:auto;left:0;border-right:none;border-left:13px solid #eee}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__line,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__line{right:auto;left:20px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-new{margin-right:0;margin-left:16px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow{right:auto;left:-12px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{right:auto;left:-10px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__arrow::after,.rtl .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-right .uagb-timeline__arrow::after,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-tablet .uagb-timeline-res-right .uagb-timeline__day-left .uagb-timeline__arrow::after{left:auto;right:0;border-left:none;border-right:13px solid #eee}}@media screen and (max-width: 767px){.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__day-new{margin-left:0;margin-right:16px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__right .uagb-timeline__arrow{left:auto;right:-10px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline__left .uagb-timeline__arrow{left:auto;right:-12px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-new,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__day-new{margin-right:0;margin-left:16px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__right .uagb-timeline__arrow{right:auto;left:-12px}.rtl .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow,[dir=rtl] .uagb-timeline__center-block.uagb-timeline__responsive-mobile .uagb-timeline-res-right .uagb-timeline__left .uagb-timeline__arrow{right:auto;left:-10px}.rtl .uagb-timeline__day-left .uagb-timeline__events-inner-new,[dir=rtl] .uagb-timeline__day-left .uagb-timeline__events-inner-new{text-align:right}.rtl .uagb-timeline__left-block .uagb-timeline__date-new,[dir=rtl] .uagb-timeline__left-block .uagb-timeline__date-new{margin-right:0;margin-left:10px}}.wp-block-uagb-container.uagb-block-83494d77 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-83494d77 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-83494d77 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-83494d77 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-83494d77 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-83494d77{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-83494d77 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-83494d77{min-height: 0px;box-shadow: 0px 0px   #00000070 ;padding-top: 144px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-eec09767 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eec09767 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eec09767 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eec09767 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eec09767 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eec09767{max-width: 66%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eec09767 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 26px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-eec09767{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 200px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 26px;column-gap: 20px;}.uagb-block-3bcc7d51 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3bcc7d51 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-3bcc7d51 .uagb-ifb-icon svg{fill: #333;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3bcc7d51 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3bcc7d51 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3bcc7d51 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3bcc7d51 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3bcc7d51 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3bcc7d51 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3bcc7d51 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-3);margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3bcc7d51 .uagb-ifb-title{font-family: \"Poppins\";margin-bottom: 36px;}.uagb-block-3bcc7d51 .uagb-ifb-desc{font-family: \"Open Sans\";color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 80px;}.uagb-block-3bcc7d51 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-3bcc7d51 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-3bcc7d51 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-3bcc7d51 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3bcc7d51 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-3bcc7d51.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-3bcc7d51 .uagb-ifb-title-prefix{font-family: \"Poppins\";text-transform: uppercase;font-weight: 500;font-size: 14px;letter-spacing: 0px;}[dir=rtl] .uagb-block-3bcc7d51 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3bcc7d51.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3bcc7d51.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-3bcc7d51.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-icon-list.uagb-block-085c02b6 .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-085c02b6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.wp-block-uagb-icon-list.uagb-block-085c02b6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-085c02b6 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-family: \"Open Sans\";text-decoration: !important;font-weight: 400;line-height: em;color: var(--ast-global-color-3);}.wp-block-uagb-icon-list.uagb-block-085c02b6 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-085c02b6 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-085c02b6 .wp-block-uagb-icon-list-child{font-family: \"Open Sans\";text-decoration: !important;font-weight: 400;line-height: em;}.wp-block-uagb-icon-list.uagb-block-085c02b6.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 31px;}.wp-block-uagb-icon-list.uagb-block-085c02b6 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-4045cc32.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: var(--ast-global-color-1) !important;color: var(--ast-global-color-1) !important;}.uagb-block-4045cc32.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-4045cc32.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-4045cc32.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-dfd569d9.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: var(--ast-global-color-1) !important;color: var(--ast-global-color-1) !important;}.uagb-block-dfd569d9.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-dfd569d9.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-dfd569d9.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-53b550d9.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: var(--ast-global-color-1) !important;color: var(--ast-global-color-1) !important;}.uagb-block-53b550d9.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-53b550d9.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-53b550d9.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-47f97ce9.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: var(--ast-global-color-1) !important;color: var(--ast-global-color-1) !important;}.uagb-block-47f97ce9.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-47f97ce9.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-47f97ce9.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 30px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-a6373acf .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-a6373acf .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.wp-block-uagb-icon-list.uagb-block-a6373acf .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-a6373acf .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-family: \"Open Sans\";text-decoration: !important;font-weight: 400;line-height: em;color: var(--ast-global-color-3);}.wp-block-uagb-icon-list.uagb-block-a6373acf .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-a6373acf .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-a6373acf .wp-block-uagb-icon-list-child{font-family: \"Open Sans\";text-decoration: !important;font-weight: 400;line-height: em;}.wp-block-uagb-icon-list.uagb-block-a6373acf.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 31px;}.wp-block-uagb-icon-list.uagb-block-a6373acf .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-89e3b5bb.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: var(--ast-global-color-1) !important;color: var(--ast-global-color-1) !important;}.uagb-block-89e3b5bb.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-89e3b5bb.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-89e3b5bb.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7b4e3012.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: var(--ast-global-color-1) !important;color: var(--ast-global-color-1) !important;}.uagb-block-7b4e3012.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-7b4e3012.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-7b4e3012.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-28ee8c23.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: var(--ast-global-color-1) !important;color: var(--ast-global-color-1) !important;}.uagb-block-28ee8c23.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-28ee8c23.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-28ee8c23.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-6de24a07.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: var(--ast-global-color-1) !important;color: var(--ast-global-color-1) !important;}.uagb-block-6de24a07.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-6de24a07.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-6de24a07.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 30px;padding-left: 0px;}.wp-block-uagb-container.uagb-block-bcb290f1 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bcb290f1 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bcb290f1 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bcb290f1 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bcb290f1 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bcb290f1{max-width: 34%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bcb290f1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-bcb290f1{box-shadow: 0px 0px   #00000070 ;padding-top: 110px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-5bdb9dae.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5bdb9dae.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-5bdb9dae.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5bdb9dae.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-5bdb9dae.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-5bdb9dae.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-5bdb9dae.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-5bdb9dae.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-5bdb9dae.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-5bdb9dae.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-5bdb9dae.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 408px;height: 502px;}.uagb-block-5bdb9dae.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-5bdb9dae.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-5bdb9dae.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5bdb9dae.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-48c4433d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-48c4433d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-48c4433d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-48c4433d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-48c4433d .uagb-container__video-wrap video{opacity: 0.6;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-48c4433d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-48c4433d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: flex-end;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-48c4433d{min-height: 287px;box-shadow: 0px 0px   #00000070 ;padding-top: 0%;padding-bottom: 24%;padding-left: 0%;padding-right: 0%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 97% 18%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/07\/plastine-operacija.png);background-clip: padding-box;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-48c4433d::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: var(--ast-global-color-6);opacity: 0.4;}.wp-block-uagb-container.uagb-block-48b87611 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-48b87611 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-48b87611 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-48b87611 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-48b87611 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-48b87611{max-width: 34%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-48b87611 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-48b87611{box-shadow: 0px 0px   #00000070 ;padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 64px;margin-top: 0% !important;margin-bottom: 0% !important;margin-left: 0%;margin-right: 0%;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-7);;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-e3fc42bb.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-e3fc42bb.wp-block-uagb-advanced-heading .uagb-desc-text{color: var(--ast-global-color-3);margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-e3fc42bb.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e3fc42bb.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e3fc42bb.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e3fc42bb .uagb-heading-text{font-family: \"Poppins\";}.wp-block-uagb-icon-list.uagb-block-cee3bce6 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-cee3bce6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-cee3bce6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-cee3bce6 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-family: \"Open Sans\";text-decoration: !important;font-weight: 400;line-height: em;color: var(--ast-global-color-3);}.wp-block-uagb-icon-list.uagb-block-cee3bce6 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-cee3bce6 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-cee3bce6 .wp-block-uagb-icon-list-child{font-family: \"Open Sans\";text-decoration: !important;font-weight: 400;line-height: em;}.wp-block-uagb-icon-list.uagb-block-cee3bce6.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 15px;}.wp-block-uagb-icon-list.uagb-block-cee3bce6 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-31eb108b.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-31eb108b.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-6791f2d9.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-6791f2d9.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-102cc8ff.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-102cc8ff.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.wp-block-uagb-container.uagb-block-22f96dfe .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-22f96dfe .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-22f96dfe .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-22f96dfe .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-22f96dfe .uagb-container__video-wrap video{opacity: 0.6;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-22f96dfe{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-22f96dfe > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: flex-end;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-22f96dfe{min-height: 287px;box-shadow: 0px 0px   #00000070 ;padding-top: 0%;padding-bottom: 24%;padding-left: 0%;padding-right: 0%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 97% 18%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/07\/plastine-operacija.png);background-clip: padding-box;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-22f96dfe::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: var(--ast-global-color-6);opacity: 0.4;}.wp-block-uagb-container.uagb-block-a79b1e46 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a79b1e46 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a79b1e46 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a79b1e46 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a79b1e46 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a79b1e46{max-width: 34%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a79b1e46 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-a79b1e46{box-shadow: 0px 0px   #00000070 ;padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 64px;margin-top: 0% !important;margin-bottom: 0% !important;margin-left: 0%;margin-right: 0%;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-7);;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-5bea738f.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-5bea738f.wp-block-uagb-advanced-heading .uagb-desc-text{color: var(--ast-global-color-3);margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-5bea738f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5bea738f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5bea738f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5bea738f .uagb-heading-text{font-family: \"Poppins\";}.wp-block-uagb-icon-list.uagb-block-4fefe354 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-4fefe354 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-4fefe354 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-4fefe354 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-family: \"Open Sans\";text-decoration: !important;font-weight: 400;line-height: em;color: var(--ast-global-color-3);}.wp-block-uagb-icon-list.uagb-block-4fefe354 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-4fefe354 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-4fefe354 .wp-block-uagb-icon-list-child{font-family: \"Open Sans\";text-decoration: !important;font-weight: 400;line-height: em;}.wp-block-uagb-icon-list.uagb-block-4fefe354.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 15px;}.wp-block-uagb-icon-list.uagb-block-4fefe354 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-4c0e62ed.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-4c0e62ed.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-923d039c.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-923d039c.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c3b3b201.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c3b3b201.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.wp-block-uagb-advanced-heading.uagb-block-a573268f.wp-block-uagb-advanced-heading {text-align: center;margin-top: 60px;margin-right: 0px;margin-bottom: 60px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a573268f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a573268f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a573268f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a573268f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a573268f .uagb-heading-text{font-family: \"Poppins\";text-transform: uppercase;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__heading{font-family: \"Open Sans\";margin-bottom: 0px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__marker.uagb-timeline__in-view-icon svg{fill: #fff;color: #fff;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__heading-text{margin-bottom: 0px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline-desc-content{font-family: \"Open Sans\";}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__day-right .uagb-timeline__arrow:after{border-left-color: #ededed00;border-right-color: #ededed00;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-left-color: #ededed00;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-left-color: #ededed00;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-left-color: #ededed00;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__center-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-right-color: #ededed00;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__left-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-right-color: #ededed00;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-left-color: #ededed00;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-left-color: #ededed00;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-left-color: #ededed00;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-right-color: #ededed00;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__day-left .uagb-timeline__arrow:after{border-right-color: #ededed00;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__line__inner{background-color: var(--ast-global-color-1);}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__line{background-color: #eee;width: 3px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__line{inset-inline-end: calc( 35px \/ 2 );}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__line{inset-inline-start: calc( 35px \/ 2 );}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__marker{background-color: #eee;min-height: 35px;min-width: 35px;line-height: 35px;border: 0px solid #eee;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__left .uagb-timeline__arrow{height: 35px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__right .uagb-timeline__arrow{height: 35px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__arrow{height: 35px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__arrow{height: 35px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__left .uagb-timeline__marker{margin-left: 10px;margin-right: 10px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__right .uagb-timeline__marker{margin-left: 10px;margin-right: 10px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__field:not(:last-child){margin-bottom: 15px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__date-hide.uagb-timeline__date-inner{font-family: \"Poppins\";font-size: 35px;margin-bottom: 5px;color: var(--ast-global-color-1);}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__date-hide.uagb-timeline__inner-date-new{font-family: \"Poppins\";font-size: 35px;margin-bottom: 5px;color: var(--ast-global-color-1);}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__day-new.uagb-timeline__day-left{margin-right: 10px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__day-new.uagb-timeline__day-left{margin-left: 10px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__day-new.uagb-timeline__day-right{margin-left: 10px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__day-new.uagb-timeline__day-right{margin-right: 10px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__date-new{font-family: \"Poppins\";font-size: 35px;color: var(--ast-global-color-1);}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__right-block .uagb-timeline__date-hide.uagb-timeline__date-inner{font-size: 35px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__left-block .uagb-timeline__date-hide.uagb-timeline__date-inner{font-size: 35px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-events-new .uagb-timeline__events-inner-new{padding: 20px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__events-inner-new{background-color: #ededed00;border-radius: 0px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__events-inner--content{padding-bottom: 0px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__marker svg{color: #333;width: 12px;fill: #333;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__marker.uagb-timeline__in-view-icon{background: var(--ast-global-color-1);border-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-block-d7f896d3 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d7f896d3 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d7f896d3 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d7f896d3 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d7f896d3 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d7f896d3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d7f896d3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d7f896d3{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-83494d77{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-83494d77 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-83494d77{padding-top: 80px;padding-bottom: 0px;padding-left: 40px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eec09767{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eec09767 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-eec09767{padding-top: 0px;padding-bottom: 40px;padding-left: 0px;padding-right: 48px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-3bcc7d51 .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3bcc7d51 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3bcc7d51 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3bcc7d51 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3bcc7d51 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3bcc7d51 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-3bcc7d51 .uagb-ifb-title-prefix{font-size: 10px;}[dir=rtl] .uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-icon-list.uagb-block-085c02b6 .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-085c02b6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;}.wp-block-uagb-icon-list.uagb-block-085c02b6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-085c02b6 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-085c02b6.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 2px;}.wp-block-uagb-icon-list.uagb-block-a6373acf .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-a6373acf .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;}.wp-block-uagb-icon-list.uagb-block-a6373acf .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-a6373acf .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-a6373acf.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 2px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bcb290f1{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bcb290f1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-bcb290f1{padding-top: 110px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-5bdb9dae.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 640px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-48c4433d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-48c4433d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;column-gap: 0px;}.wp-block-uagb-container.uagb-block-48c4433d{padding-top: 0%;padding-bottom: 24%;padding-left: 6%;padding-right: 0%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/07\/plastine-operacija.png);background-clip: padding-box;column-gap: 0px;}.wp-block-uagb-container.uagb-block-48c4433d::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-6);opacity: 0.4;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-48b87611{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-48b87611 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-48b87611{padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 64px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-7);;}.wp-block-uagb-icon-list.uagb-block-cee3bce6 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-cee3bce6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-cee3bce6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-cee3bce6 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-cee3bce6.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 15px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-22f96dfe{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-22f96dfe > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;column-gap: 0px;}.wp-block-uagb-container.uagb-block-22f96dfe{padding-top: 0%;padding-bottom: 24%;padding-left: 6%;padding-right: 0%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/07\/plastine-operacija.png);background-clip: padding-box;column-gap: 0px;}.wp-block-uagb-container.uagb-block-22f96dfe::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-6);opacity: 0.4;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a79b1e46{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a79b1e46 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a79b1e46{padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 64px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-7);;}.wp-block-uagb-icon-list.uagb-block-4fefe354 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-4fefe354 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-4fefe354 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-4fefe354 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-4fefe354.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 15px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-right-color: #ededed00;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__marker{background-color: #eee;border: 0px solid #eee;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d7f896d3{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d7f896d3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d7f896d3{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-83494d77{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-83494d77 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;justify-content: flex-start;flex-wrap: nowrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-83494d77{padding-top: 64px;padding-bottom: 0px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;order: initial;}.wp-block-uagb-container.uagb-block-83494d77.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-83494d77.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eec09767{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eec09767 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-eec09767{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-eec09767.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-eec09767.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.uagb-block-3bcc7d51 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 20px;}.uagb-block-3bcc7d51 .uagb-ifb-desc{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 40px;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3bcc7d51 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3bcc7d51 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3bcc7d51 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3bcc7d51 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3bcc7d51 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3bcc7d51.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-icon-list.uagb-block-085c02b6 .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-085c02b6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;}.wp-block-uagb-icon-list.uagb-block-085c02b6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-085c02b6 .uagb-icon-list__wrap{display: flex;flex-direction: row;justify-content: flex-start;-webkit-box-pack: flex-start;-ms-flex-pack: flex-start;-webkit-box-align: center;-ms-flex-align: center;align-items: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-085c02b6.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 10px;margin-right: 10px;display: inline-flex;}.wp-block-uagb-icon-list.uagb-block-085c02b6.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child:first-child{margin-left: 0;}.wp-block-uagb-icon-list.uagb-block-a6373acf .uagb-icon-list__source-image{width: 14px;}.wp-block-uagb-icon-list.uagb-block-a6373acf .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-a6373acf .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 14px;height: 14px;font-size: 14px;}.wp-block-uagb-icon-list.uagb-block-a6373acf .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-a6373acf .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-a6373acf.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bcb290f1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bcb290f1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-bcb290f1{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-5bdb9dae.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 831px;height: auto;}.uagb-block-5bdb9dae.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-48c4433d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-48c4433d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column-reverse;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-48c4433d{padding-top: 0px;padding-bottom: 420px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-position: 52% 58%;background-image: url(https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/07\/plastine-operacija.png);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-48c4433d::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-6);opacity: 0.4;}.wp-block-uagb-container.uagb-block-48c4433d.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-48c4433d.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-48b87611{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-48b87611 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-48b87611{padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 64px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-7);;flex-wrap: wrap;}.wp-block-uagb-icon-list.uagb-block-cee3bce6 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-cee3bce6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-cee3bce6 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-cee3bce6 .uagb-icon-list__wrap{display: flex;flex-direction: row;justify-content: flex-start;-webkit-box-pack: flex-start;-ms-flex-pack: flex-start;-webkit-box-align: center;-ms-flex-align: center;align-items: center;}.wp-block-uagb-icon-list.uagb-block-cee3bce6.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 7.5px;margin-right: 7.5px;display: inline-flex;}.wp-block-uagb-icon-list.uagb-block-cee3bce6.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child:first-child{margin-left: 0;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-22f96dfe{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-22f96dfe > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 0px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column-reverse;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-22f96dfe{min-height: 0px;padding-top: 0px;padding-bottom: 420px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-position: 43% 38%;background-size: auto;background-image: url(https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/07\/plastine-operacija.png);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-22f96dfe::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-6);opacity: 0.4;}.wp-block-uagb-container.uagb-block-22f96dfe.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-22f96dfe.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a79b1e46{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a79b1e46 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a79b1e46{padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 64px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-7);;}.wp-block-uagb-icon-list.uagb-block-4fefe354 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-4fefe354 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-4fefe354 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-4fefe354 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-4fefe354.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 15px;}.uagb-block-1350e29f.uagb-timeline__outer-wrap.uagb-timeline__center-block .uagb-timeline__day-right .uagb-timeline__arrow:after{border-right-color: #ededed00;}.uagb-block-1350e29f.uagb-timeline__outer-wrap .uagb-timeline__marker{background-color: #eee;border: 0px solid #eee;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d7f896d3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d7f896d3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d7f896d3{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.uagb-block-3ddaf554 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3ddaf554 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-3ddaf554 .uagb-ifb-icon svg{fill: #333;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3ddaf554 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3ddaf554 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3ddaf554 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3ddaf554 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3ddaf554 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3ddaf554 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3ddaf554 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-3ddaf554 .uagb-ifb-title{font-size: 24px;color: var(--ast-global-color-0);margin-bottom: 10px;}.uagb-block-3ddaf554 .uagb-ifb-desc{color: var(--ast-global-color-0);margin-bottom: 20px;}.uagb-block-3ddaf554 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-3ddaf554 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-3ddaf554 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-3ddaf554 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3ddaf554 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-3ddaf554.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3ddaf554 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3ddaf554 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3ddaf554 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3ddaf554 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3ddaf554 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ddaf554 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3ddaf554 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ddaf554 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3ddaf554 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3ddaf554 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3ddaf554 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-694046dc .uagb-ifb-icon svg{fill: #333;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-694046dc .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-694046dc .uagb-ifb-desc{color: var(--ast-global-color-0);margin-bottom: 20px;}.uagb-block-694046dc .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-694046dc .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-694046dc .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-694046dc .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-infobox__content-wrap{text-align: left;}.uagb-block-694046dc.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-694046dc.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-694046dc .uagb-ifb-icon svg{fill: #333;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-694046dc .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-694046dc .uagb-ifb-desc{color: var(--ast-global-color-0);margin-bottom: 20px;}.uagb-block-694046dc .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-694046dc .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-694046dc .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-694046dc .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-infobox__content-wrap{text-align: left;}.uagb-block-694046dc.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-694046dc.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-advanced-heading.uagb-block-dc4a9001.wp-block-uagb-advanced-heading {margin-bottom: -50px;padding-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-dc4a9001.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-dc4a9001.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-dc4a9001.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-dc4a9001.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.uagb-block-c66cdb91 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c66cdb91 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-c66cdb91 .uagb-ifb-icon svg{fill: #333;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c66cdb91 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c66cdb91 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c66cdb91 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c66cdb91 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c66cdb91 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c66cdb91 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c66cdb91 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-c66cdb91 .uagb-ifb-title{font-family: \"Poppins\";font-size: 24px;color: var(--ast-global-color-0);margin-bottom: 10px;}.uagb-block-c66cdb91 .uagb-ifb-desc{color: var(--ast-global-color-2);margin-bottom: 20px;}.uagb-block-c66cdb91 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-c66cdb91 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-c66cdb91 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-c66cdb91 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c66cdb91 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-c66cdb91.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-c66cdb91 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c66cdb91 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c66cdb91 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-c66cdb91 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-c66cdb91 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c66cdb91 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-c66cdb91 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c66cdb91 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c66cdb91 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c66cdb91 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-c66cdb91 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-694046dc .uagb-ifb-icon svg{fill: #333;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-694046dc .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-694046dc .uagb-ifb-desc{font-family: \"Poppins\";font-size: 16px;color: var(--ast-global-color-2);margin-bottom: 20px;}.uagb-block-694046dc .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-694046dc .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-694046dc .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-694046dc .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-infobox__content-wrap{text-align: left;}.uagb-block-694046dc.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-694046dc.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-buttons__outer-wrap .uagb-buttons__wrap{display:inline-flex;width:100%}.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}@media(max-width: 976px){.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}@media(max-width: 767px){.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}.uagb-buttons__outer-wrap .uagb-buttons-repeater{display:flex;justify-content:center;align-items:center;transition:box-shadow .2s ease}.uagb-buttons__outer-wrap .uagb-buttons-repeater a.uagb-button__link{display:flex;justify-content:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon{font-size:inherit;display:flex;align-items:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon svg{fill:currentColor;width:inherit;height:inherit}.uagb-block-5ae6b4a9.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-5ae6b4a9.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-5ea173fd.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-5ea173fd.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-button__link{text-transform: normal;text-decoration: none;}@media only screen and (max-width: 976px) {.uagb-block-5ae6b4a9.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-5ae6b4a9.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-5ea173fd.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}@media only screen and (max-width: 767px) {.uagb-block-5ae6b4a9.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-5ae6b4a9.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-5ea173fd.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;line-height: em;color: var(--ast-global-color-3);}.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .wp-block-uagb-icon-list-child{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-272e24a2.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 5px;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-591e8179.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #63637a !important;color: #63637a !important;}.uagb-block-591e8179.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: var(--ast-global-color-3) !important;}.uagb-block-591e8179.wp-block-uagb-icon-list-child:hover .uagb-icon-list__label{color: var(--ast-global-color-3) !important;}.uagb-block-591e8179.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-591e8179.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-8efe3fd9.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #63637a !important;color: #63637a !important;}.uagb-block-8efe3fd9.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-8efe3fd9.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-eef5eca3.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #63637a !important;color: #63637a !important;}.uagb-block-eef5eca3.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-eef5eca3.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-ff10b1f9.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #63637a !important;color: #63637a !important;}.uagb-block-ff10b1f9.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-ff10b1f9.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-94b38bed.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #63637a !important;color: #63637a !important;}.uagb-block-94b38bed.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-94b38bed.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-272e24a2.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 5px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__label{text-align: center;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;margin-top: -30px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-icon-list.uagb-block-272e24a2.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 5px;}}.uagb-block-5eb4bbe8.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-5eb4bbe8.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-5eb4bbe8 .uagb-buttons-repeater:not(.wp-block-button__link){font-weight: 400;font-size: 16px;}.uagb-block-5eb4bbe8 .uagb-button__wrapper .uagb-buttons-repeater.wp-block-button__link{font-weight: 400;font-size: 16px;}.uagb-block-5eb4bbe8 .uagb-button__wrapper .uagb-buttons-repeater.ast-outline-button{font-weight: 400;font-size: 16px;}.uagb-block-5eb4bbe8 .uagb-button__wrapper{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .wp-block-button__link:hover{background: #63637a;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .wp-block-button__link:focus{background: #63637a;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 18px;padding-bottom: 15px;padding-left: 70px;padding-right: 70px;margin-top: -20px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: -20px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-b4dc9b13.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-b4dc9b13.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-button__link{text-transform: normal;text-decoration: none;}@media only screen and (max-width: 976px) {.uagb-block-5eb4bbe8.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-5eb4bbe8.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-b4dc9b13.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}@media only screen and (max-width: 767px) {.uagb-block-5eb4bbe8.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-5eb4bbe8.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-b4dc9b13.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}\";s:2:\"js\";s:700:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener(\"DOMContentLoaded\", function(){\n\tUAGBTimelineClasses( {\"block_id\":\"1350e29f\",\"timelinAlignment\":\"center\",\"timelinAlignmentTablet\":\"left\",\"timelinAlignmentMobile\":\"left\"}, '.uagb-block-1350e29f' );\n});\nwindow.addEventListener(\"resize\", function(){\n\tUAGBTimelineClasses( {\"block_id\":\"1350e29f\",\"timelinAlignment\":\"center\",\"timelinAlignmentTablet\":\"left\",\"timelinAlignmentMobile\":\"left\"}, '.uagb-block-1350e29f' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-5ea173fd' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-b4dc9b13' );\n});\n });\";s:18:\"current_block_list\";a:19:{i:0;s:14:\"uagb\/container\";i:2;s:13:\"uagb\/info-box\";i:3;s:14:\"uagb\/icon-list\";i:4;s:20:\"uagb\/icon-list-child\";i:6;s:10:\"uagb\/image\";i:9;s:21:\"uagb\/advanced-heading\";i:10;s:21:\"uagb\/content-timeline\";i:11;s:27:\"uagb\/content-timeline-child\";i:13;s:11:\"core\/spacer\";i:14;s:11:\"core\/search\";i:15;s:10:\"core\/group\";i:16;s:12:\"core\/heading\";i:17;s:17:\"core\/latest-posts\";i:18;s:20:\"core\/latest-comments\";i:19;s:13:\"core\/archives\";i:20;s:15:\"core\/categories\";i:21;s:14:\"core\/paragraph\";i:22;s:12:\"uagb\/buttons\";i:23;s:18:\"uagb\/buttons-child\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1783166229\";s:6:\"gfonts\";a:2:{s:7:\"Poppins\";a:2:{s:10:\"fontfamily\";s:7:\"Poppins\";s:12:\"fontvariants\";a:1:{i:0;s:3:\"500\";}}s:9:\"Open Sans\";a:2:{s:10:\"fontfamily\";s:9:\"Open Sans\";s:12:\"fontvariants\";a:1:{i:0;s:3:\"400\";}}}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"JoAst-1","author_link":"https:\/\/drmaslauskas.com\/en\/author\/joast-1\/"},"uagb_comment_info":0,"uagb_excerpt":"Associations: Associations: International experience:","_links":{"self":[{"href":"https:\/\/drmaslauskas.com\/en\/wp-json\/wp\/v2\/pages\/5270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drmaslauskas.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/drmaslauskas.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/drmaslauskas.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/drmaslauskas.com\/en\/wp-json\/wp\/v2\/comments?post=5270"}],"version-history":[{"count":4,"href":"https:\/\/drmaslauskas.com\/en\/wp-json\/wp\/v2\/pages\/5270\/revisions"}],"predecessor-version":[{"id":5285,"href":"https:\/\/drmaslauskas.com\/en\/wp-json\/wp\/v2\/pages\/5270\/revisions\/5285"}],"wp:attachment":[{"href":"https:\/\/drmaslauskas.com\/en\/wp-json\/wp\/v2\/media?parent=5270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}