{"id":5333,"date":"2024-07-11T05:55:05","date_gmt":"2024-07-11T05:55:05","guid":{"rendered":"https:\/\/drmaslauskas.com\/breast-implant-surgery\/"},"modified":"2024-10-29T14:43:16","modified_gmt":"2024-10-29T14:43:16","slug":"breast-implant-surgery","status":"publish","type":"page","link":"https:\/\/drmaslauskas.com\/en\/breast-implant-surgery\/","title":{"rendered":"Breast implant surgery"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uag-hide-desktop uag-hide-tab uagb-block-b684f5c3 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uag-hide-desktop uag-hide-tab uagb-block-3f469eee alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7eb23bac\"><h1 class=\"uagb-heading-text\">Breast implant surgery<\/h1><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uag-hide-mob uagb-block-4a3d3c55 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-662fc7a2\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-65e3bc45\"><h1 class=\"uagb-heading-text\">Breast implant surgery<\/h1><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uag-hide-mob uagb-block-f7feb64f alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<p class=\"wp-block-paragraph\">Breast implant surgery is an aesthetic surgery procedure that remains one of the most popular worldwide. Breasts have always been considered one of the symbols of femininity, and thanks to modern medicine it is even easier to achieve the desired look, get rid of complexes and enjoy greater self-confidence.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Breast augmentation with implants is available when:<\/p>\n\n\n\n<ul style=\"padding-right:var(--wp--preset--spacing--60);padding-left:var(--wp--preset--spacing--60)\" class=\"wp-block-list\">\n<li>Breast enlargement is wanted.<\/li>\n\n\n\n<li>The aim is to flatten asymmetrical (unequal-sized or shaped) breasts.<\/li>\n\n\n\n<li>The aim is to restore the shape of the breasts after pregnancy or breastfeeding, after weight loss or during the ageing process.<\/li>\n\n\n\n<li>To shape the breasts after a mastectomy (partial removal of one or both breasts).<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">However, sometimes breast implants alone cannot give the desired result &#8211; this is often the case after pregnancy and childbirth, when not only the size of the breasts changes but also their shape and firmness. In this case, two surgeries can be combined at the same time &#8211; a <a href=\"https:\/\/drmaslauskas.com\/en\/breast-lift\/\">breast lift<\/a> and a breast augmentation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Breast augmentation surgery can be performed together with <a href=\"https:\/\/drmaslauskas.com\/en\/fat-transfer-breast-augmentation\/\">fat grafting breast augmentation.<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uag-hide-desktop uag-hide-tab uagb-block-790677ce alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<p class=\"wp-block-paragraph\" style=\"margin-top:0;margin-bottom:0;padding-top:0;padding-bottom:0\">Breast implant surgery is an aesthetic surgery procedure that remains one of the most popular worldwide. Breasts have always been considered one of the symbols of femininity, and thanks to modern medicine it is even easier to achieve the desired look, get rid of complexes and enjoy greater self-confidence.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Breast augmentation with implants is available when:<\/p>\n\n\n\n<ul style=\"padding-top:0;padding-right:var(--wp--preset--spacing--60);padding-bottom:0;padding-left:var(--wp--preset--spacing--60)\" class=\"wp-block-list\">\n<li>Breast enlargement is wanted.<\/li>\n\n\n\n<li>The aim is to flatten asymmetrical (unequal-sized or shaped) breasts.<\/li>\n\n\n\n<li>The aim is to restore the shape of the breasts after pregnancy or breastfeeding, after weight loss or during the ageing process.<\/li>\n\n\n\n<li>To shape the breasts after a mastectomy (partial removal of one or both breasts).<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">However, sometimes breast implants alone cannot give the desired result &#8211; this is often the case after pregnancy and childbirth, when not only the size of the breasts changes but also their shape and firmness. In this case, two surgeries can be combined at the same time &#8211; a <a href=\"https:\/\/drmaslauskas.com\/en\/breast-lift\/\">breast lift<\/a> and a breast augmentation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Breast augmentation surgery can be performed together with <a href=\"https:\/\/drmaslauskas.com\/en\/fat-transfer-breast-augmentation\/\">fat grafting breast augmentation.<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-1a5e9b9d alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fb040251\"><h2 class=\"uagb-heading-text\">The process of breast implant surgery<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-tabs uagb-block-185bbe61 uagb-tabs__wrap uagb-tabs__hstyle3-desktop uagb-tabs__vstyle6-tablet uagb-tabs__stack1-mobile\" data-tab-active=\"0\"><ul class=\"uagb-tabs__panel uagb-tabs__align-left\" role=\"tablist\"><li class=\"uagb-tab uagb-tabs__active\" role=\"none\"><a href=\"#uagb-tabs__tab0\" class=\"uagb-tabs-list uagb-tabs__icon-position-left\" data-tab=\"0\" role=\"tab\"><div>1<\/div><\/a><\/li><li class=\"uagb-tab \" role=\"none\"><a href=\"#uagb-tabs__tab1\" class=\"uagb-tabs-list uagb-tabs__icon-position-left\" data-tab=\"1\" role=\"tab\"><div>2<\/div><\/a><\/li><\/ul><div class=\"uagb-tabs__body-wrap\">\n<div class=\"wp-block-uagb-tabs-child uagb-tabs__body-container uagb-inner-tab-0\" aria-labelledby=\"uagb-tabs__tab0\">\n<p class=\"wp-block-paragraph\">Breast augmentation is performed under general anaesthesia. On average, breast augmentation surgery takes 1-1.5 hours. <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-tabs-child uagb-tabs__body-container uagb-inner-tab-1\" aria-labelledby=\"uagb-tabs__tab1\">\n<p class=\"wp-block-paragraph\">Breast augmentation surgery is optionally performed through the areola (the darker area around the nipple), under the breast or in the armpit. After the incision is made during the surgery, a lodge is formed in the breast area into which the implant is inserted. Breast implants are usually placed partly under the muscle and partly under the gland. Once the implant is in place, the incision is sutured and repaired. A scar forms at the incision site, but over time it becomes lighter and less visible.     <\/p>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-bc5b94d8 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-3aa44ff0\">\n<div class=\"wp-block-uagb-info-box uagb-block-cfc3a24a uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Before surgery<\/h2><\/div><p class=\"uagb-ifb-desc\">Before undergoing breast augmentation surgery, it is important to choose the right size and shape of the implant. The breast implants used for this surgery meet the highest quality standards. <br><br>It is crucial for the patient to have realistic expectations, as breast augmentation surgery is anatomy-limited. Implants are chosen based on patient preference, chest wall shape, and breast sagging, not just desires.<br><br>It is recommended to perform a breast echoscopy before surgery.<\/p><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0424776f alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-5cfd56e6 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Post-surgery period<\/h2><\/div><p class=\"uagb-ifb-desc\">Patients can go home the next day. Resting for about a week after surgery is recommended. For a few weeks after surgery, the breasts may be sensitive, swollen and painful, which is a normal condition that will subside with time. Showering after 3 days is possible, but it is important to change the bandages after bathing. After the surgery, a special bra must be worn for 3 months to support the breasts. It is also advisable not to do any active sports for 3 months, sleep on your stomach, lift your arms suddenly, kneel, stretch or push heavy objects.     <br><br>After breast augmentation with implants, it is recommended to visit the plastic surgeon who performed the surgery every year for an examination and breast echoscopy.<\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-8952eeba uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Surgical risk<\/h2><\/div><p class=\"uagb-ifb-desc\">The risk of breast implant surgery is not high. However, as after any other interventional procedure, complications such as bleeding, infection, pain, fluid accumulation, hypersensitivity in the chest area, allergic reactions to anaesthesia, rupture or repositioning of the implant, and hardening of the chest as a result of scarring may occur. All these complications can usually be avoided by following the surgeon&#8217;s recommendations after surgery.  <\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-6c0c8d46\"><h2 class=\"uagb-heading-text\">Results<\/h2><\/div>\n\n\n\n<p class=\"has-text-align-left has-ast-global-color-3-color has-text-color has-link-color wp-elements-c988ed09d3d87a1accfbccd66fd46b70 wp-block-paragraph\">The initial result is visible immediately after the breast implant surgery, but the final result is not assessed until 6-12 months later.<\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-c43e3f9f alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><div id=\"metaslider-id-4620\" style=\"width: 100%;\" class=\"ml-slider-3-110-0 metaslider metaslider-flex metaslider-4620 ml-slider hide-navigation-smartphone has-dots-nav has-carousel-mode ms-theme-default\" role=\"region\" aria-label=\"Kr\u016bt\u0173 didinimas implantais\" data-height=\"300\" data-width=\"300\">\n    <div id=\"metaslider_container_4620\">\n        <div id=\"metaslider_4620\">\n            <ul class='slides'>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4691 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:50\" data-filename=\"krutu-didinimas-39-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-39-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4691 msDefaultImage\" title=\"krutu-didinimas-39\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4692 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:50\" data-filename=\"krutu-didinimas-40-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-40-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4692 msDefaultImage\" title=\"krutu-didinimas-40\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4693 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:50\" data-filename=\"krutu-didinimas-41-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-41-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4693 msDefaultImage\" title=\"krutu-didinimas-41\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4694 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:50\" data-filename=\"krutu-didinimas-42-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-42-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4694 msDefaultImage\" title=\"krutu-didinimas-42\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4695 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:50\" data-filename=\"krutu-didinimas-43-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-43-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4695 msDefaultImage\" title=\"krutu-didinimas-43\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4696 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:50\" data-filename=\"krutu-didinimas-44-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-44-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4696 msDefaultImage\" title=\"krutu-didinimas-44\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4697 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:50\" data-filename=\"krutu-didinimas-45-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-45-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4697 msDefaultImage\" title=\"krutu-didinimas-45\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4698 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:50\" data-filename=\"krutu-didinimas-46-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-46-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4698 msDefaultImage\" title=\"krutu-didinimas-46\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4699 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:50\" data-filename=\"krutu-didinimas-47-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-47-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4699 msDefaultImage\" title=\"krutu-didinimas-47\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4700 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:50\" data-filename=\"krutu-didinimas-48-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-48-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4700 msDefaultImage\" title=\"krutu-didinimas-48\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4701 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:50\" data-filename=\"krutu-didinimas-49-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-49-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4701 msDefaultImage\" title=\"krutu-didinimas-49\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4702 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:50\" data-filename=\"krutu-didinimas-50-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-50-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4702 msDefaultImage\" title=\"krutu-didinimas-50\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4703 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:50\" data-filename=\"krutu-didinimas-51-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-51-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4703 msDefaultImage\" title=\"krutu-didinimas-51\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4704 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:50\" data-filename=\"krutu-didinimas-52-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-52-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4704 msDefaultImage\" title=\"krutu-didinimas-52\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4705 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:50\" data-filename=\"krutu-didinimas-53-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-53-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4705 msDefaultImage\" title=\"krutu-didinimas-53\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4706 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:51\" data-filename=\"krutu-didinimas-54-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-54-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4706 msDefaultImage\" title=\"krutu-didinimas-54\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4707 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:51\" data-filename=\"krutu-didinimas-55-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-55-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4707 msDefaultImage\" title=\"krutu-didinimas-55\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4708 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:51\" data-filename=\"krutu-didinimas-56-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-56-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4708 msDefaultImage\" title=\"krutu-didinimas-56\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4709 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:51\" data-filename=\"krutu-didinimas-57-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-57-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4709 msDefaultImage\" title=\"krutu-didinimas-57\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4710 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:51\" data-filename=\"krutu-didinimas-58-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-58-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4710 msDefaultImage\" title=\"krutu-didinimas-58\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4711 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:51\" data-filename=\"krutu-didinimas-59-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-59-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4711 msDefaultImage\" title=\"krutu-didinimas-59\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4712 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:51\" data-filename=\"krutu-didinimas-60-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-60-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4712 msDefaultImage\" title=\"krutu-didinimas-60\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4713 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:51\" data-filename=\"krutu-didinimas-61-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-61-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4713 msDefaultImage\" title=\"krutu-didinimas-61\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4714 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:51\" data-filename=\"krutu-didinimas-62-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-62-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4714 msDefaultImage\" title=\"krutu-didinimas-62\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4715 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:51\" data-filename=\"krutu-didinimas-63-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-63-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4715 msDefaultImage\" title=\"krutu-didinimas-63\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4716 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:51\" data-filename=\"krutu-didinimas-64-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-64-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4716 msDefaultImage\" title=\"krutu-didinimas-64\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4717 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:51\" data-filename=\"krutu-didinimas-65-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-65-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4717 msDefaultImage\" title=\"krutu-didinimas-65\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4718 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:51\" data-filename=\"krutu-didinimas-66-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-66-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4718 msDefaultImage\" title=\"krutu-didinimas-66\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4719 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:51\" data-filename=\"krutu-didinimas-67-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-67-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4719 msDefaultImage\" title=\"krutu-didinimas-67\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4720 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:51\" data-filename=\"krutu-didinimas-68-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-68-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4720 msDefaultImage\" title=\"krutu-didinimas-68\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4721 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:52\" data-filename=\"krutu-didinimas-69-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-69-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4721 msDefaultImage\" title=\"krutu-didinimas-69\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4722 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:52\" data-filename=\"krutu-didinimas-70-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-70-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4722 msDefaultImage\" title=\"krutu-didinimas-70\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4723 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:52\" data-filename=\"krutu-didinimas-71-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-71-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4723 msDefaultImage\" title=\"krutu-didinimas-71\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4724 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:52\" data-filename=\"krutu-didinimas-72-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-72-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4724 msDefaultImage\" title=\"krutu-didinimas-72\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4725 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 10:22:52\" data-filename=\"krutu-didinimas-73-300x300.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/10\/krutu-didinimas-73-300x300.png\" height=\"300\" width=\"300\" alt=\"Kr\u016bt\u0173 didinimas\" class=\"slider-4620 slide-4725 msDefaultImage\" title=\"krutu-didinimas-73\" \/><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-caa60b3b\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-95d398e8 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/drmaslauskas.com\/en\/breast-implant-surgery-gallery\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">SEE MORE<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ccfe4d01\"><h2 class=\"uagb-heading-text\">Frequently asked questions<\/h2><\/div>\n\n\n<div class=\"wp-block-uagb-faq uagb-faq__outer-wrap uagb-block-9ae6b2ea uagb-faq-icon-row-reverse uagb-faq-layout-accordion uagb-faq-expand-first-false uagb-faq-inactive-other-true uagb-faq__wrap uagb-buttons-layout-wrap uagb-faq-equal-height     \" data-faqtoggle=\"true\" role=\"tablist\"><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-3df71a78 \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 384 512\"><path d=\"M352 352c-8.188 0-16.38-3.125-22.62-9.375L192 205.3l-137.4 137.4c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25l160-160c12.5-12.5 32.75-12.5 45.25 0l160 160c12.5 12.5 12.5 32.75 0 45.25C368.4 348.9 360.2 352 352 352z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 384 512\"><path d=\"M192 384c-8.188 0-16.38-3.125-22.62-9.375l-160-160c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L192 306.8l137.4-137.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-160 160C208.4 380.9 200.2 384 192 384z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<h3 class=\"uagb-question\">What is the likelihood of needing breast augmentation again in the future?<\/h3><\/div><div class=\"uagb-faq-content\"><p>The need for repeated breast augmentation depends on various factors, such as the type of implants and the patient&#8217;s individual situation and lifestyle. On average, up to 20% of women who have undergone breast augmentation surgery may need a second surgery within a 10-year period. The most common reasons for needing repeated breast implant surgery and breast lift are implant rupture, capsule formation, the desire to change the size or shape of the implant, changes in the shape of the breasts due to weight gain or loss, and ageing processes.  <\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-54e35db7 \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 384 512\"><path d=\"M352 352c-8.188 0-16.38-3.125-22.62-9.375L192 205.3l-137.4 137.4c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25l160-160c12.5-12.5 32.75-12.5 45.25 0l160 160c12.5 12.5 12.5 32.75 0 45.25C368.4 348.9 360.2 352 352 352z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 384 512\"><path d=\"M192 384c-8.188 0-16.38-3.125-22.62-9.375l-160-160c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L192 306.8l137.4-137.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-160 160C208.4 380.9 200.2 384 192 384z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<h3 class=\"uagb-question\">Can I breastfeed if I have had breast augmentation with implants?<\/h3><\/div><div class=\"uagb-faq-content\"><p>Most women who have undergone breast augmentation surgery can breastfeed successfully, but this depends on the incision site and the technique of the surgery. If the incision is made through the areola, this can increase the risk of breastfeeding difficulty, as the technique damages part of the milk ducts. <\/p><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Breast implant surgery Breast implant surgery Breast implant surgery is an aesthetic surgery procedure that remains one of the most popular worldwide. Breasts have always been considered one of the symbols of femininity, and thanks to modern medicine it is even easier to achieve the desired look, get rid of complexes and enjoy greater self-confidence. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5593,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-5333","page","type-page","status-publish","has-post-thumbnail","hentry"],"spectra_custom_meta":{"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"adv-header-id-meta":[""],"stick-header-meta":[""],"theme-transparent-header-meta":[""],"ast-site-content-layout":["default"],"_last_translation_edit_mode":["native-editor"],"_edit_lock":["1730212997:2"],"_uag_custom_page_level_css":[""],"astra-migrate-meta-layouts":["set"],"_themeisle_gutenberg_block_has_review":[""],"footnotes":[""],"_edit_last":["2"],"_wpml_media_has_media":["1"],"_wp_page_template":[""],"_uag_css_file_name":["uag-css-5333.css"],"_uag_js_file_name":["uag-js-5333.js"],"rank_math_title":["Breast Implant Surgery | K\u0119stutis Maslauskas"],"rank_math_description":["Breast implant surgery: increasing breast size, correcting symmetry, and reshaping the chest after pregnancy, breastfeeding, or mastectomy."],"rank_math_focus_keyword":["breast implant surgery"],"rank_math_news_sitemap_robots":["index"],"rank_math_robots":["a:1:{i:0;s:5:\"index\";}"],"rank_math_seo_score":["66"],"_thumbnail_id":["5593"],"rank_math_internal_links_processed":["1"],"_uag_page_assets":["a:9:{s:3:\"css\";s:173526:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.uagb-tabs__wrap{display:flex}.uagb-tabs__wrap ul.uagb-tabs__panel{margin:0;list-style-type:none;display:inherit}.uagb-tabs__wrap ul.uagb-tabs__panel.uagb-tabs__align-center{justify-content:center}.uagb-tabs__wrap ul.uagb-tabs__panel.uagb-tabs__align-left{justify-content:flex-start}.uagb-tabs__wrap ul.uagb-tabs__panel.uagb-tabs__align-right{justify-content:flex-end}.uagb-tabs__wrap ul.uagb-tabs__panel.uagb-tabs__align-right .uagb-tab:last-child{margin-right:0}.uagb-tabs__wrap ul.uagb-tabs__panel li.uagb-tab a{position:relative;padding:6px 12px;display:inline-flex;color:inherit}.uagb-tabs__wrap ul.uagb-tabs__panel li.uagb-tab a.uagb-tabs__icon-position-top{display:block}.uagb-tabs__wrap ul.uagb-tabs__panel li.uagb-tab a.uagb-tabs__icon-position-top .uagb-tabs__icon{display:block}.uagb-tabs__wrap ul.uagb-tabs__panel li.uagb-tab a.uagb-tabs__icon-position-bottom{display:block}.uagb-tabs__wrap ul.uagb-tabs__panel li.uagb-tab a.uagb-tabs__icon-position-bottom .uagb-tabs__icon{display:block}.uagb-tabs__wrap ul.uagb-tabs__panel p{margin:0}.uagb-tabs__wrap ul.uagb-tabs__panel .uagb-tabs__icon{vertical-align:text-top}.uagb-tabs__wrap ul.uagb-tabs__panel .uagb-tabs__icon-position-left{display:block;align-items:center}.uagb-tabs__wrap ul.uagb-tabs__panel .uagb-tabs__icon-position-left .uagb-tabs__icon{display:flex;align-self:center}.uagb-tabs__wrap ul.uagb-tabs__panel .uagb-tabs__icon-position-right{display:block}.uagb-tabs__wrap ul.uagb-tabs__panel .uagb-tabs__icon-position-right .uagb-tabs__icon{display:flex;align-self:center}.uagb-tabs__wrap .uagb-tabs__body-wrap{position:relative;max-width:100%;padding:10px}.editor-styles-wrapper .uagb-tabs__wrap .uagb-tabs-editor-controls{display:none}.editor-styles-wrapper .uagb-tabs__wrap li.uagb-tab:hover .uagb-tabs-editor-controls{display:flex}.editor-styles-wrapper .uagb-editor-preview-mode-tablet.uagb-tabs__wrap li.uagb-tab.uagb-tabs__add-tab,.editor-styles-wrapper .uagb-editor-preview-mode-mobile.uagb-tabs__wrap li.uagb-tab.uagb-tabs__add-tab{display:none}.uagb-tabs__wrap.uagb-tabs__hstyle1-desktop,.uagb-tabs__wrap.uagb-tabs__hstyle2-desktop,.uagb-tabs__wrap.uagb-tabs__hstyle3-desktop,.uagb-tabs__wrap.uagb-tabs__hstyle4-desktop,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop{flex-direction:column}.uagb-tabs__wrap.uagb-tabs__hstyle1-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle2-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle3-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle4-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop ul.uagb-tabs__panel{margin-bottom:0;padding:0;display:flex;align-items:center;flex-direction:row;max-width:100%;flex-wrap:wrap}.uagb-tabs__wrap.uagb-tabs__hstyle1-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle2-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle3-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle4-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop .uagb-tabs__body-wrap{max-width:100%}.uagb-tabs__wrap.uagb-tabs__hstyle1-desktop .uagb-tab{margin:10px 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__hstyle2-desktop .uagb-tab{margin:10px 10px -1px 0}.uagb-tabs__wrap.uagb-tabs__hstyle2-desktop .uagb-tabs__body-wrap{border:none}.uagb-tabs__wrap.uagb-tabs__hstyle3-desktop .uagb-tab{margin:10px 10px 0 0}.uagb-tabs__wrap.uagb-tabs__hstyle4-desktop .uagb-tab{margin:10px 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop ul.uagb-tabs__panel{justify-content:space-between;margin:0}.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop .uagb-tab{margin:10px 10px 10px 10px;text-align:center}.uagb-tabs__wrap.uagb-tabs__vstyle6-desktop,.uagb-tabs__wrap.uagb-tabs__vstyle7-desktop,.uagb-tabs__wrap.uagb-tabs__vstyle8-desktop,.uagb-tabs__wrap.uagb-tabs__vstyle9-desktop,.uagb-tabs__wrap.uagb-tabs__vstyle10-desktop{flex-direction:row}.uagb-tabs__wrap.uagb-tabs__vstyle6-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle7-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle8-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle9-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle10-desktop ul.uagb-tabs__panel{padding:0;display:flex;flex-direction:column;flex-grow:1;flex-wrap:wrap}.uagb-tabs__wrap.uagb-tabs__vstyle6-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle7-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle8-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle9-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle10-desktop .uagb-tabs__body-wrap{flex-grow:3}.uagb-tabs__wrap.uagb-tabs__vstyle6-desktop .uagb-tabs-list,.uagb-tabs__wrap.uagb-tabs__vstyle7-desktop .uagb-tabs-list,.uagb-tabs__wrap.uagb-tabs__vstyle8-desktop .uagb-tabs-list,.uagb-tabs__wrap.uagb-tabs__vstyle9-desktop .uagb-tabs-list,.uagb-tabs__wrap.uagb-tabs__vstyle10-desktop .uagb-tabs-list{width:-webkit-fill-available;justify-content:center}.uagb-tabs__wrap.uagb-tabs__vstyle6-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle7-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle9-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle10-desktop ul.uagb-tabs__panel{min-width:24%;max-width:24%;margin:0}.uagb-tabs__wrap.uagb-tabs__vstyle6-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle7-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle9-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle10-desktop .uagb-tabs__body-wrap{max-width:75%}.uagb-tabs__wrap.uagb-tabs__vstyle6-desktop .uagb-tab{margin:0 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__vstyle7-desktop .uagb-tab{margin:10px 10px 0 0}.uagb-tabs__wrap.uagb-tabs__vstyle8-desktop ul.uagb-tabs__panel{min-width:25%;max-width:25%}.uagb-tabs__wrap.uagb-tabs__vstyle8-desktop .uagb-tabs__body-wrap{max-width:75%}.uagb-tabs__wrap.uagb-tabs__vstyle9-desktop .uagb-tab{margin:0 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__vstyle10-desktop .uagb-tab{margin:10px 10px 10px 10px;text-align:center}@media(max-width: 1023px){.uagb-tabs__wrap.uagb-tabs__hstyle1-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle2-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle3-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle4-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle5-tablet{flex-direction:column}.uagb-tabs__wrap.uagb-tabs__hstyle1-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle2-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle3-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle4-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle5-tablet ul.uagb-tabs__panel{margin-bottom:0;padding:0;max-width:100%;display:flex;flex-direction:row;flex-wrap:wrap}.uagb-tabs__wrap.uagb-tabs__hstyle1-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle2-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle3-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle4-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle5-tablet .uagb-tabs__body-wrap{max-width:100%}.uagb-tabs__wrap.uagb-tabs__hstyle1-tablet .uagb-tab{margin:10px 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__hstyle2-tablet .uagb-tab{margin:10px 10px -1px 0}.uagb-tabs__wrap.uagb-tabs__hstyle3-tablet .uagb-tab{margin:10px 10px 0 0}.uagb-tabs__wrap.uagb-tabs__hstyle4-tablet .uagb-tab{margin:10px 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__hstyle5-tablet ul.uagb-tabs__panel{justify-content:flex-start;margin:0}.uagb-tabs__wrap.uagb-tabs__hstyle5-tablet .uagb-tab{margin:10px 10px 10px 10px;text-align:center}.uagb-tabs__wrap.uagb-tabs__vstyle6-tablet,.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet,.uagb-tabs__wrap.uagb-tabs__vstyle8-tablet,.uagb-tabs__wrap.uagb-tabs__vstyle9-tablet,.uagb-tabs__wrap.uagb-tabs__vstyle10-tablet{flex-direction:row}.uagb-tabs__wrap.uagb-tabs__vstyle6-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle8-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle9-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle10-tablet ul.uagb-tabs__panel{margin-bottom:0;padding:0;display:flex;flex-direction:column;flex-grow:1}.uagb-tabs__wrap.uagb-tabs__vstyle6-tablet .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__vstyle8-tablet .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__vstyle9-tablet .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__vstyle10-tablet .uagb-tab p{margin:0}.uagb-tabs__wrap.uagb-tabs__vstyle6-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle8-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle9-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle10-tablet .uagb-tabs__body-wrap{flex-grow:3}.uagb-tabs__wrap.uagb-tabs__vstyle6-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle9-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle10-tablet ul.uagb-tabs__panel{min-width:24%;max-width:24%}.uagb-tabs__wrap.uagb-tabs__vstyle6-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle9-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle10-tablet .uagb-tabs__body-wrap{max-width:75%}.uagb-tabs__wrap.uagb-tabs__vstyle6-tablet .uagb-tabs__body-wrap .uagb-tabs-list,.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet .uagb-tabs__body-wrap .uagb-tabs-list,.uagb-tabs__wrap.uagb-tabs__vstyle9-tablet .uagb-tabs__body-wrap .uagb-tabs-list,.uagb-tabs__wrap.uagb-tabs__vstyle10-tablet .uagb-tabs__body-wrap .uagb-tabs-list{width:-webkit-fill-available;justify-content:center}.uagb-tabs__wrap.uagb-tabs__vstyle6-tablet .uagb-tab{margin:0 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet ul.uagb-tabs__panel{margin:0}.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet ul.uagb-tabs__panel .uagb-tab{margin:10px 10px 0 0}.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet .uagb-tabs__body-wrap{border:none}.uagb-tabs__wrap.uagb-tabs__vstyle8-tablet ul.uagb-tabs__panel{margin-bottom:0;min-width:25%;max-width:25%;justify-content:normal}.uagb-tabs__wrap.uagb-tabs__vstyle9-tablet ul.uagb-tabs__panel{margin-bottom:0}.uagb-tabs__wrap.uagb-tabs__vstyle9-tablet ul.uagb-tabs__panel .uagb-tab{margin:0 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__vstyle10-tablet ul.uagb-tabs__panel{margin:0}.uagb-tabs__wrap.uagb-tabs__vstyle10-tablet ul.uagb-tabs__panel .uagb-tab{margin:10px 10px 10px 10px;text-align:center}.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__hstyle3-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__hstyle4-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__hstyle3-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__hstyle4-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__vstyle6-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__vstyle8-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__vstyle9-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__vstyle6-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__vstyle8-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__vstyle9-tablet .uagb-tabs__body-wrap{border-style:none}}@media(max-width: 767px){.uagb-tabs__wrap.uagb-tabs__hstyle1-mobile,.uagb-tabs__wrap.uagb-tabs__hstyle2-mobile,.uagb-tabs__wrap.uagb-tabs__hstyle3-mobile,.uagb-tabs__wrap.uagb-tabs__hstyle4-mobile,.uagb-tabs__wrap.uagb-tabs__hstyle5-mobile{flex-direction:column;border-style:none}.uagb-tabs__wrap.uagb-tabs__hstyle1-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle2-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle3-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle4-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle5-mobile ul.uagb-tabs__panel{margin-bottom:0;padding:0;display:flex;flex-direction:row;flex-grow:1;max-width:100%}.uagb-tabs__wrap.uagb-tabs__hstyle1-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle2-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle3-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle4-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle5-mobile .uagb-tabs__body-wrap{flex-direction:row;max-width:100%}.uagb-tabs__wrap.uagb-tabs__vstyle6-mobile,.uagb-tabs__wrap.uagb-tabs__vstyle7-mobile,.uagb-tabs__wrap.uagb-tabs__vstyle8-mobile,.uagb-tabs__wrap.uagb-tabs__vstyle9-mobile,.uagb-tabs__wrap.uagb-tabs__vstyle10-mobile{flex-direction:row;border-style:none}.uagb-tabs__wrap.uagb-tabs__vstyle6-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle7-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle8-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle9-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle10-mobile ul.uagb-tabs__panel{margin-bottom:0;padding:0;display:flex;flex-direction:column;flex-grow:1}.uagb-tabs__wrap.uagb-tabs__vstyle6-mobile .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__vstyle7-mobile .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__vstyle8-mobile .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__vstyle9-mobile .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__vstyle10-mobile .uagb-tab p{margin:0}.uagb-tabs__wrap.uagb-tabs__vstyle6-mobile .uagb-tab .uagb-tabs-list,.uagb-tabs__wrap.uagb-tabs__vstyle7-mobile .uagb-tab .uagb-tabs-list,.uagb-tabs__wrap.uagb-tabs__vstyle8-mobile .uagb-tab .uagb-tabs-list,.uagb-tabs__wrap.uagb-tabs__vstyle9-mobile .uagb-tab .uagb-tabs-list,.uagb-tabs__wrap.uagb-tabs__vstyle10-mobile .uagb-tab .uagb-tabs-list{width:-webkit-fill-available;justify-content:center}.uagb-tabs__wrap.uagb-tabs__vstyle6-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle7-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle8-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle9-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle10-mobile .uagb-tabs__body-wrap{flex-grow:3;max-width:75%}.uagb-tabs__wrap.uagb-tabs__hstyle1-mobile .uagb-tab{margin:10px 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__hstyle2-mobile .uagb-tab{margin:10px 10px -1px 0}.uagb-tabs__wrap.uagb-tabs__hstyle3-mobile .uagb-tab{margin:10px 10px 0 0}.uagb-tabs__wrap.uagb-tabs__hstyle4-mobile .uagb-tab{margin:10px 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__hstyle5-mobile ul.uagb-tabs__panel{justify-content:flex-start;margin:0}.uagb-tabs__wrap.uagb-tabs__hstyle5-mobile .uagb-tab{margin:10px 10px 10px 10px;text-align:center}.uagb-tabs__wrap.uagb-tabs__vstyle6-mobile ul.uagb-tabs__panel{min-width:24%;max-width:24%}.uagb-tabs__wrap.uagb-tabs__vstyle6-mobile ul.uagb-tabs__panel .uagb-tab{margin:0 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__vstyle7-mobile ul.uagb-tabs__panel{min-width:24%;max-width:24%;margin:0}.uagb-tabs__wrap.uagb-tabs__vstyle7-mobile ul.uagb-tabs__panel .uagb-tab{margin:10px 10px 0 0}.uagb-tabs__wrap.uagb-tabs__vstyle8-mobile ul.uagb-tabs__panel{min-width:24%;max-width:24%}.uagb-tabs__wrap.uagb-tabs__vstyle8-mobile ul.uagb-tabs__panel .uagb-tab{margin:0 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__vstyle9-mobile ul.uagb-tabs__panel{min-width:24%;max-width:24%}.uagb-tabs__wrap.uagb-tabs__vstyle9-mobile ul.uagb-tabs__panel .uagb-tab{margin:0 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__vstyle10-mobile ul.uagb-tabs__panel{min-width:24%;max-width:24%;margin:0}.uagb-tabs__wrap.uagb-tabs__vstyle10-mobile ul.uagb-tabs__panel .uagb-tab{margin:10px 10px 10px 10px;text-align:center}.uagb-tabs__wrap.uagb-tabs__stack1-mobile,.uagb-tabs__wrap.uagb-tabs__stack2-mobile,.uagb-tabs__wrap.uagb-tabs__stack3-mobile,.uagb-tabs__wrap.uagb-tabs__stack4-mobile{display:block}.uagb-tabs__wrap.uagb-tabs__stack1-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__stack2-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__stack3-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__stack4-mobile ul.uagb-tabs__panel{margin:0;padding:0;display:flex;flex-direction:column;max-width:100%;flex-grow:unset}.uagb-tabs__wrap.uagb-tabs__stack1-mobile ul.uagb-tabs__panel .uagb-tab,.uagb-tabs__wrap.uagb-tabs__stack2-mobile ul.uagb-tabs__panel .uagb-tab,.uagb-tabs__wrap.uagb-tabs__stack3-mobile ul.uagb-tabs__panel .uagb-tab,.uagb-tabs__wrap.uagb-tabs__stack4-mobile ul.uagb-tabs__panel .uagb-tab{width:100%}.uagb-tabs__wrap.uagb-tabs__stack1-mobile ul.uagb-tabs__panel .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__stack2-mobile ul.uagb-tabs__panel .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__stack3-mobile ul.uagb-tabs__panel .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__stack4-mobile ul.uagb-tabs__panel .uagb-tab p{margin:0}.uagb-tabs__wrap.uagb-tabs__stack1-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__stack2-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__stack3-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__stack4-mobile .uagb-tabs__body-wrap{max-width:100%}.uagb-tabs__wrap.uagb-tabs__stack1-mobile{display:block}.uagb-tabs__wrap.uagb-tabs__stack1-mobile ul.uagb-tabs__panel{margin:0;padding:0;display:flex;flex-direction:column;max-width:100%;flex-grow:unset}.uagb-tabs__wrap.uagb-tabs__stack1-mobile ul.uagb-tabs__panel .uagb-tab{margin:0 0 10px 0}.uagb-tabs__wrap.uagb-tabs__stack1-mobile ul.uagb-tabs__panel .uagb-tab p{margin:0}.uagb-tabs__wrap.uagb-tabs__stack1-mobile .uagb-tabs__body-wrap{max-width:100%}.uagb-tabs__wrap.uagb-tabs__stack2-mobile ul.uagb-tabs__panel .uagb-tab{margin:0 0 10px 0}.uagb-tabs__wrap.uagb-tabs__stack3-mobile ul.uagb-tabs__panel .uagb-tab{margin:0 0 10px 0;padding:6px 12px 6px 12px}.uagb-tabs__wrap.uagb-tabs__stack4-mobile{margin:auto}.uagb-tabs__wrap.uagb-tabs__stack4-mobile ul.uagb-tabs__panel .uagb-tab{margin:0 0 10px 0;text-align:center}}.uagb-tabs__wrap .uagb-tabs__body-container.uagb-tabs-body__active{display:block}.uagb-tabs__wrap .uagb-tabs__body-container{padding:10px 15px;display:none}.uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}.uagb-buttons__outer-wrap .uagb-buttons__wrap{display:inline-flex;width:100%}.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}@media(max-width: 976px){.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}@media(max-width: 767px){.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}.uagb-buttons__outer-wrap .uagb-buttons-repeater{display:flex;justify-content:center;align-items:center;transition:box-shadow .2s ease}.uagb-buttons__outer-wrap .uagb-buttons-repeater a.uagb-button__link{display:flex;justify-content:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon{font-size:inherit;display:flex;align-items:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon svg{fill:currentColor;width:inherit;height:inherit}.wp-block-uagb-faq{width:100%}.wp-block-uagb-faq.uagb-faq-layout-accordion .uagb-faq-child__outer-wrap .uagb-faq-questions-button{cursor:pointer}.wp-block-uagb-faq .uagb-faq-content{margin-bottom:0}.wp-block-uagb-faq .uagb-faq-content p{margin:auto}.uagb-faq-layout-grid.uagb-faq-equal-height.uagb-faq__wrap .uagb-faq-child__outer-wrap,.uagb-faq-layout-grid.uagb-faq-equal-height.uagb-faq__wrap .uagb-faq-item{height:100%}body[class*=astra] .uagb-faq-questions{line-height:normal}.uagb-faq-item{overflow:hidden}.wp-block-uagb-faq-child .uagb-faq-questions-button{display:flex;align-items:center}.wp-block-uagb-faq-child .uagb-faq-questions-button .uagb-faq-icon-wrap{display:flex;align-items:center}.wp-block-uagb-faq-child .uagb-faq-questions-button .uagb-question{width:100%;margin-top:0;margin-bottom:0}.wp-block-uagb-faq-child .uagb-icon svg,.wp-block-uagb-faq-child .uagb-icon-active svg{width:15px;height:15px;font-size:15px}.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item .uagb-icon-active,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item .uagb-icon-active,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon{display:none;width:0;height:0;margin:0}.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item .uagb-icon,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon-active,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item .uagb-icon,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon-active{display:flex;width:auto;height:auto}.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item .uagb-icon,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon-active,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item .uagb-icon,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon-active{display:none}.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item span.uagb-icon-active.uagb-faq-icon-wrap,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon-active,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item span.uagb-icon-active.uagb-faq-icon-wrap,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon-active{display:none}.wp-block-uagb-container.uagb-block-b684f5c3 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b684f5c3 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b684f5c3 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b684f5c3 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b684f5c3 .uagb-container__video-wrap video{opacity: 0.8;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b684f5c3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b684f5c3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1004px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: flex-end;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-b684f5c3{min-height: 0px;box-shadow: 0px 0px   #00000070 ;padding-top: 0%;padding-bottom: 0%;padding-left: 0%;padding-right: 0%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 58% 85%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/09\/krutu-didinimas-implantais-4.png);background-clip: padding-box;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-b684f5c3::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: #e6e6e6;opacity: 0.2;}.wp-block-uagb-container.uagb-block-3f469eee .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3f469eee .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3f469eee .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3f469eee .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3f469eee .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3f469eee{max-width: 38%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3f469eee > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row-reverse;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3f469eee{box-shadow: 0px 0px   #00000070 ;padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 84px;margin-top: 20% !important;margin-bottom: 0% !important;margin-left: 0%;margin-right: 60%;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-7eb23bac.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-7eb23bac.wp-block-uagb-advanced-heading .uagb-desc-text{color: var(--ast-global-color-3);margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-7eb23bac.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7eb23bac.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7eb23bac.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7eb23bac .uagb-heading-text{font-family: \"Poppins\";font-size: 40px;}.wp-block-uagb-container.uagb-block-4a3d3c55 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4a3d3c55 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4a3d3c55 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4a3d3c55 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4a3d3c55 .uagb-container__video-wrap video{opacity: 0.8;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a3d3c55{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a3d3c55 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1004px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: flex-end;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4a3d3c55{min-height: 0px;box-shadow: 0px 0px   #00000070 ;padding-top: 0%;padding-bottom: 0%;padding-left: 0%;padding-right: 0%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 49% 45%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/09\/krutu-didinimas-implantais-4.png);background-clip: padding-box;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4a3d3c55::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: #e6e6e6;opacity: 0.2;}.wp-block-uagb-container.uagb-block-662fc7a2 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-662fc7a2 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-662fc7a2 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-662fc7a2 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-662fc7a2 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-662fc7a2{max-width: 38%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-662fc7a2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row-reverse;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-662fc7a2{box-shadow: 0px 0px   #00000070 ;padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top: 20% !important;margin-bottom: 0% !important;margin-left: 0%;margin-right: 60%;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;flex-direction: row-reverse;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-65e3bc45.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-65e3bc45.wp-block-uagb-advanced-heading .uagb-desc-text{color: var(--ast-global-color-3);margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-65e3bc45.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-65e3bc45.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-65e3bc45.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-65e3bc45 .uagb-heading-text{font-family: \"Poppins\";font-size: 40px;}.wp-block-uagb-container.uagb-block-f7feb64f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f7feb64f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f7feb64f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f7feb64f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f7feb64f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f7feb64f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f7feb64f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-f7feb64f{box-shadow: 0px 0px   #00000070 ;padding-top: 60px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-790677ce .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-790677ce .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-790677ce .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-790677ce .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-790677ce .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-790677ce{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-790677ce > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-790677ce{box-shadow: 0px 0px   #00000070 ;padding-top: 60px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-1a5e9b9d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1a5e9b9d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1a5e9b9d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1a5e9b9d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1a5e9b9d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1a5e9b9d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1a5e9b9d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-1a5e9b9d{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-fb040251.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-fb040251.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-fb040251.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fb040251.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fb040251.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fb040251 .uagb-heading-text{font-family: \"Poppins\";text-transform: uppercase;font-weight: 500;font-size: 24px;}.uagb-block-185bbe61 .uagb-tabs__panel .uagb-tab {background: var(--ast-global-color-6);text-align: left;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61 .uagb-tabs__panel .uagb-tab .uagb-tabs-list{justify-content: left;}.uagb-block-185bbe61.uagb-tabs__wrap ul.uagb-tabs__panel li.uagb-tab a {color: var(--ast-global-color-4);}.uagb-block-185bbe61 .uagb-tabs__panel .uagb-tab.uagb-tabs__active{background: #63637a;}.uagb-block-185bbe61.uagb-tabs__wrap ul.uagb-tabs__panel li.uagb-tab.uagb-tabs__active a{color: var(--ast-global-color-4);}.uagb-block-185bbe61 .uagb-tabs__icon svg{height: 16px;width: 16px;}.uagb-block-185bbe61 .uagb-tabs__icon-position-left > .uagb-tabs__icon{margin-right: 10px;}.uagb-block-185bbe61 .uagb-tabs__icon-position-right > .uagb-tabs__icon{margin-left: 10px;}.uagb-block-185bbe61 .uagb-tabs__icon-position-bottom > .uagb-tabs__icon{margin-top: 10px;}.uagb-block-185bbe61 .uagb-tabs__icon-position-top > .uagb-tabs__icon{margin-bottom: 10px;}.uagb-block-185bbe61.uagb-tabs__hstyle1-desktop > .uagb-tabs__panel .uagb-tab{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61.uagb-tabs__hstyle1-desktop > .uagb-tabs__body-wrap{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61.uagb-tabs__hstyle2-desktop > .uagb-tabs__panel .uagb-tab{border-width: 0px;border-style: none;}.uagb-block-185bbe61.uagb-tabs__hstyle2-desktop ul.uagb-tabs__panel{border-top-width: 1px;border-right-width: 1px;border-left-width: 1px;border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61.uagb-tabs__hstyle2-desktop > .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-185bbe61.uagb-tabs__hstyle3-desktop .uagb-tab{border-bottom-width: 1px;border-bottom: 0;outline: 0;border-radius: 0;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61.uagb-tabs__hstyle3-desktop > .uagb-tabs__body-wrap{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61.uagb-tabs__hstyle4-desktop .uagb-tab{border-radius: 30px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61.uagb-tabs__hstyle4-desktop > .uagb-tabs__body-wrap{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61.uagb-tabs__hstyle5-desktop{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61.uagb-tabs__hstyle5-desktop .uagb-tab{border-top-width: 0px;border-right-width: 0px;border-left-width: 0px;border-bottom-width: 0px;border-top: 0;border-left: 0;border-right: 0;border-bottom: 0;outline: 0;border-radius: 0;}.uagb-block-185bbe61.uagb-tabs__hstyle5-desktop .uagb-tab.uagb-tabs__active{border-top-width: 1px;border-right-width: 1px;border-left-width: 1px;border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61.uagb-tabs__vstyle6-desktop .uagb-tab{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61.uagb-tabs__vstyle6-desktop .uagb-tabs__body-wrap{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61.uagb-tabs__vstyle7-desktop .uagb-tab{border-top-width: 1px;border-right-width: 1px;border-left-width: 1px;border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61.uagb-tabs__vstyle7-desktop > .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-185bbe61.uagb-tabs__vstyle8-desktop .uagb-tab{border-right-width: 1px;border-right: 0;outline: 0;border-radius: 0;border-top-width: 1px;border-left-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61.uagb-tabs__vstyle8-desktop > .uagb-tabs__body-wrap{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61.uagb-tabs__vstyle9-desktop .uagb-tab{border-radius: 30px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61.uagb-tabs__vstyle9-desktop > .uagb-tabs__body-wrap{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61.uagb-tabs__vstyle10-desktop{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61.uagb-tabs__vstyle10-desktop ul.uagb-tabs__panel .uagb-tab{border-width: 0px;border-style: none;}.uagb-block-185bbe61.uagb-tabs__vstyle10-desktop .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-185bbe61.uagb-tabs__vstyle10-desktop ul.uagb-tabs__panel .uagb-tab.uagb-tabs__active{border-top-width: 1px;border-bottom-width: 1px;border-left-width: 1px;border-top: 0;border-left: 0;border-bottom: 0;outline: 0;border-radius: 0;border-right-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-6);border-style: solid;}.uagb-block-185bbe61 ul.uagb-tabs__panel{margin-right: auto;margin-left: 0;}.uagb-block-185bbe61  .uagb-tabs__panel .uagb-tab a{font-weight: 500;}.wp-block-uagb-container.uagb-block-bc5b94d8 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bc5b94d8 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bc5b94d8 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bc5b94d8 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bc5b94d8 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bc5b94d8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bc5b94d8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-bc5b94d8{box-shadow: 0px 0px   #00000070 ;padding-top: 50px;padding-bottom: 50px;padding-left: 50px;padding-right: 50px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: ;;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3aa44ff0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3aa44ff0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3aa44ff0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3aa44ff0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3aa44ff0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3aa44ff0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3aa44ff0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3aa44ff0{box-shadow: 0px 18px 40px -10px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-7);;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-cfc3a24a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-cfc3a24a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-cfc3a24a .uagb-ifb-icon svg{fill: #333;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cfc3a24a .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cfc3a24a .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-cfc3a24a .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cfc3a24a .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cfc3a24a .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-cfc3a24a .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-cfc3a24a .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-2);margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-cfc3a24a .uagb-ifb-title{font-family: \"Poppins\";text-transform: uppercase;font-weight: 500;font-size: 24px;color: var(--ast-global-color-1);margin-bottom: 10px;}.uagb-block-cfc3a24a .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-cfc3a24a .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-cfc3a24a .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-cfc3a24a .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-cfc3a24a .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-cfc3a24a .uagb-infobox__content-wrap{text-align: left;}.uagb-block-cfc3a24a.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 20px;padding-right: 20px;padding-bottom: 20px;padding-left: 20px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 20px;padding-right: 20px;padding-bottom: 20px;padding-left: 20px;margin-top: 0px;margin-right: 60px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-cfc3a24a .uagb-ifb-title-prefix{font-family: \"Poppins\";font-weight: 600;font-size: 12px;letter-spacing: 2px;}[dir=rtl] .uagb-block-cfc3a24a .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cfc3a24a.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cfc3a24a.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-cfc3a24a.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-0424776f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0424776f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0424776f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0424776f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0424776f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0424776f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0424776f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: wrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-0424776f{box-shadow: 0px 0px   #00000070 ;padding-top: 70px;padding-bottom: 70px;padding-left: 70px;padding-right: 70px;margin-top: 30px !important;margin-bottom: 60px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-6);;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-0424776f::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;mix-blend-mode: normal;background-clip: padding-box;opacity: 1;}.uagb-block-5cfd56e6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-5cfd56e6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-5cfd56e6 .uagb-ifb-icon svg{fill: #333;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-5cfd56e6 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-5cfd56e6 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-5cfd56e6 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-5cfd56e6 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-5cfd56e6 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-5cfd56e6 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-5cfd56e6 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-2);margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-5cfd56e6 .uagb-ifb-title{text-transform: uppercase;font-weight: 500;font-size: 24px;color: var(--ast-global-color-4);margin-bottom: 10px;}.uagb-block-5cfd56e6 .uagb-ifb-desc{color: var(--ast-global-color-4);margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-5cfd56e6 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-5cfd56e6 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-5cfd56e6 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-5cfd56e6 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-5cfd56e6 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-5cfd56e6.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{margin-top: 10px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-5cfd56e6 .uagb-ifb-title-prefix{font-family: \"Poppins\";font-weight: 600;font-size: 12px;letter-spacing: 2px;}[dir=rtl] .uagb-block-5cfd56e6 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5cfd56e6.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5cfd56e6.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-5cfd56e6.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-8952eeba .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8952eeba .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-8952eeba .uagb-ifb-icon svg{fill: #333;}.uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8952eeba .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8952eeba .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8952eeba .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8952eeba .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8952eeba .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8952eeba .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-8952eeba.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8952eeba .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-2);margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-8952eeba .uagb-ifb-title{text-transform: uppercase;font-weight: 500;font-size: 24px;color: var(--ast-global-color-4);margin-bottom: 10px;}.uagb-block-8952eeba .uagb-ifb-desc{color: var(--ast-global-color-4);margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-8952eeba .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-8952eeba .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-8952eeba .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-8952eeba .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8952eeba .uagb-infobox__content-wrap{text-align: left;}.uagb-block-8952eeba.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-8952eeba.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-8952eeba .uagb-ifb-title-prefix{font-family: \"Poppins\";font-weight: 600;font-size: 12px;letter-spacing: 2px;}[dir=rtl] .uagb-block-8952eeba .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8952eeba.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8952eeba.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-8952eeba.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-6c0c8d46.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-6c0c8d46.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-6c0c8d46.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6c0c8d46.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6c0c8d46.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6c0c8d46 .uagb-heading-text{font-family: \"Poppins\";text-transform: uppercase;font-weight: 500;font-size: 20px;}.wp-block-uagb-container.uagb-block-c43e3f9f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c43e3f9f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c43e3f9f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c43e3f9f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c43e3f9f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c43e3f9f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c43e3f9f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c43e3f9f{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.uagb-block-caa60b3b.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-caa60b3b.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.wp-block-uagb-buttons .uagb-block-95d398e8 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-95d398e8 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-95d398e8 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-95d398e8 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-95d398e8 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-95d398e8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-95d398e8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-95d398e8 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;}.wp-block-uagb-buttons .uagb-block-95d398e8 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-95d398e8 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-95d398e8 .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-advanced-heading.uagb-block-ccfe4d01.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-ccfe4d01.wp-block-uagb-advanced-heading {padding-top: 60px;padding-right: 0px;padding-bottom: 20px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ccfe4d01.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ccfe4d01.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ccfe4d01.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ccfe4d01.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ccfe4d01 .uagb-heading-text{text-transform: uppercase;font-weight: 500;font-size: 20px;}.uagb-block-9ae6b2ea .uagb-icon svg{width: 12px;height: 12px;font-size: 12px;}.uagb-block-9ae6b2ea .uagb-icon-active svg{width: 12px;height: 12px;font-size: 12px;}.uagb-block-9ae6b2ea .uagb-faq-child__outer-wrap{margin-bottom: 14px;}.uagb-block-9ae6b2ea .uagb-faq-item{background-color: transparent;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #D2D2D2;border-style: solid;}.uagb-block-9ae6b2ea .uagb-faq-questions-button{padding-top: 15px;padding-bottom: 15px;padding-right: 15px;padding-left: 15px;}.uagb-block-9ae6b2ea .uagb-faq-content{padding-top: 0px;padding-bottom: 15px;padding-right: 15px;padding-left: 15px;}.uagb-block-9ae6b2ea .uagb-faq-content span{margin-top: 0px;margin-bottom: 15px;margin-right: 15px;margin-left: 15px;}.uagb-block-9ae6b2ea.uagb-faq-icon-row .uagb-faq-item .uagb-faq-icon-wrap{margin-right: 17px;}.uagb-block-9ae6b2ea.uagb-faq-icon-row-reverse .uagb-faq-item .uagb-faq-icon-wrap{margin-left: 17px;}.uagb-block-9ae6b2ea .uagb-faq-item .uagb-faq-questions-button.uagb-faq-questions{flex-direction: row-reverse;}.uagb-block-9ae6b2ea .uagb-faq-item .uagb-faq-content{color: var(--ast-global-color-1);}.uagb-block-9ae6b2ea.uagb-faq__outer-wrap{margin-top: 0px;margin-right: 100px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 60px;padding-left: 0px;}.uagb-block-9ae6b2ea .wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-content {display: none;}.uagb-block-9ae6b2ea .uagb-faq-questions-button .uagb-question{font-family: \"Poppins\";font-weight: 400;font-size: 18px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-b684f5c3{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b684f5c3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;column-gap: 0px;}.wp-block-uagb-container.uagb-block-b684f5c3{padding-top: 0%;padding-bottom: 24%;padding-left: 6%;padding-right: 0%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/09\/krutu-didinimas-implantais-4.png);background-clip: padding-box;column-gap: 0px;}.wp-block-uagb-container.uagb-block-b684f5c3::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #e6e6e6;opacity: 0.2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3f469eee{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3f469eee > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3f469eee{padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 64px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a3d3c55{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a3d3c55 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4a3d3c55{padding-top: 0%;padding-bottom: 24%;padding-left: 6%;padding-right: 0%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/09\/krutu-didinimas-implantais-4.png);background-clip: padding-box;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4a3d3c55::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #e6e6e6;opacity: 0.2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-662fc7a2{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-662fc7a2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-662fc7a2{padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 64px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f7feb64f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f7feb64f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-f7feb64f{padding-top: 60px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-790677ce{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-790677ce > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-790677ce{padding-top: 60px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1a5e9b9d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1a5e9b9d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1a5e9b9d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-185bbe61.uagb-tabs__hstyle1-tablet > .uagb-tabs__panel .uagb-tab{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__hstyle1-tablet > .uagb-tabs__body-wrap{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__hstyle2-tablet > .uagb-tabs__panel .uagb-tab{border-width: 0px;border-style: none;}.uagb-block-185bbe61.uagb-tabs__hstyle2-tablet ul.uagb-tabs__panel{border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__hstyle2-tablet > .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-185bbe61.uagb-tabs__hstyle3-tablet .uagb-tab{border-bottom: 0;outline: 0;border-radius: 0;border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__hstyle3-tablet > .uagb-tabs__body-wrap{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__hstyle4-tablet .uagb-tab{border-radius: 30px;border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__hstyle4-tablet > .uagb-tabs__body-wrap{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__hstyle5-tablet{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__hstyle5-tablet .uagb-tab{border-top-width: 0px;border-right-width: 0px;border-left-width: 0px;border-bottom-width: 0px;border-top: 0;border-left: 0;border-right: 0;border-bottom: 0;outline: 0;border-radius: 0;}.uagb-block-185bbe61.uagb-tabs__hstyle5-tablet .uagb-tab.uagb-tabs__active{border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle6-tablet > .uagb-tabs__panel .uagb-tab{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle6-tablet > .uagb-tabs__body-wrap{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle7-tablet .uagb-tab{border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle7-tablet > .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-185bbe61.uagb-tabs__vstyle8-tablet .uagb-tab{border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle8-tablet > .uagb-tabs__body-wrap{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle9-tablet .uagb-tab{border-radius: 30px;border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle9-tablet > .uagb-tabs__body-wrap{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle10-tablet{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle10-tablet ul.uagb-tabs__panel .uagb-tab{border-width: 0px;border-style: none;}.uagb-block-185bbe61.uagb-tabs__vstyle10-tablet .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-185bbe61.uagb-tabs__vstyle10-tablet ul.uagb-tabs__panel .uagb-tab.uagb-tabs__active{border-top: 0;border-left: 0;border-bottom: 0;outline: 0;border-radius: 0;border-style: solid;border-color: var(--ast-global-color-6);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bc5b94d8{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bc5b94d8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-bc5b94d8{padding-top: 50px;padding-bottom: 50px;padding-left: 50px;padding-right: 50px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: ;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3aa44ff0{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3aa44ff0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3aa44ff0{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-7);;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-cfc3a24a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-cfc3a24a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-cfc3a24a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-cfc3a24a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cfc3a24a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-cfc3a24a .uagb-ifb-title-prefix{font-size: 10px;}[dir=rtl] .uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0424776f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0424776f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-0424776f{padding-top: 70px;padding-bottom: 70px;padding-left: 70px;padding-right: 70px;margin-top: 30px !important;margin-bottom: 60px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-6);;}.wp-block-uagb-container.uagb-block-0424776f::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);mix-blend-mode: normal;background-clip: padding-box;opacity: 1;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-5cfd56e6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-5cfd56e6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-5cfd56e6 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-5cfd56e6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5cfd56e6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-5cfd56e6 .uagb-ifb-title-prefix{font-size: 10px;}[dir=rtl] .uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8952eeba .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8952eeba .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-8952eeba .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-8952eeba .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8952eeba .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-8952eeba .uagb-ifb-title-prefix{font-size: 10px;}[dir=rtl] .uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c43e3f9f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c43e3f9f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c43e3f9f{padding-top: 0px;padding-bottom: 0px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-caa60b3b.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-caa60b3b.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-95d398e8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-95d398e8 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}.uagb-block-9ae6b2ea.uagb-faq-icon-row .uagb-faq-item .uagb-faq-icon-wrap{margin-right: 10px;}.uagb-block-9ae6b2ea.uagb-faq-icon-row-reverse .uagb-faq-item .uagb-faq-icon-wrap{margin-left: 10px;}.uagb-block-9ae6b2ea .uagb-faq-questions-button{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-9ae6b2ea .uagb-faq-content{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-9ae6b2ea .uagb-faq-content span{margin-top: 10px;margin-bottom: 10px;margin-right: 10px;margin-left: 10px;}.uagb-block-9ae6b2ea .uagb-faq-item{border-style: solid;border-color: #D2D2D2;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-b684f5c3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b684f5c3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1600px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column-reverse;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b684f5c3{min-height: 0px;padding-top: 0px;padding-bottom: 450px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-position: 49% 69%;background-image: url(https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/09\/krutu-didinimas-implantais-5.png);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-b684f5c3::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #e6e6e6;opacity: 0.2;}.wp-block-uagb-container.uagb-block-b684f5c3.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-b684f5c3.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3f469eee{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3f469eee > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3f469eee{padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 64px;margin-top: -100px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a3d3c55{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a3d3c55 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column-reverse;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4a3d3c55{padding-top: 0px;padding-bottom: 420px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/drmaslauskas.com\/wp-content\/uploads\/2024\/09\/krutu-didinimas-implantais-4.png);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-4a3d3c55::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #e6e6e6;opacity: 0.2;}.wp-block-uagb-container.uagb-block-4a3d3c55.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-4a3d3c55.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-662fc7a2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-662fc7a2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-662fc7a2{padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 64px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f7feb64f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f7feb64f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f7feb64f{padding-top: 60px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-790677ce{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-790677ce > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-790677ce{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1a5e9b9d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1a5e9b9d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1a5e9b9d{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-185bbe61.uagb-tabs__hstyle1-mobile > .uagb-tabs__panel .uagb-tab{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__hstyle1-mobile > .uagb-tabs__body-wrap{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__hstyle2-mobile > .uagb-tabs__panel .uagb-tab{border-width: 0px;border-style: none;}.uagb-block-185bbe61.uagb-tabs__hstyle2-mobile ul.uagb-tabs__panel{border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__hstyle2-mobile > .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-185bbe61.uagb-tabs__hstyle3-mobile .uagb-tab{border-bottom: 0;outline: 0;border-radius: 0;border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__hstyle3-mobile > .uagb-tabs__body-wrap{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__hstyle4-mobile .uagb-tab{border-radius: 30px;border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__hstyle4-mobile > .uagb-tabs__body-wrap{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__hstyle5-mobile{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__hstyle5-mobile .uagb-tab{border-top-width: 0px;border-right-width: 0px;border-left-width: 0px;border-bottom-width: 0px;border-top: 0;border-left: 0;border-right: 0;border-bottom: 0;outline: 0;border-radius: 0;}.uagb-block-185bbe61.uagb-tabs__hstyle5-mobile .uagb-tab.uagb-tabs__active{border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle6-mobile .uagb-tab{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle6-mobile .uagb-tabs__body-wrap{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle7-mobile .uagb-tab{border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle7-mobile > .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-185bbe61.uagb-tabs__vstyle8-mobile .uagb-tab{border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle8-mobile > .uagb-tabs__body-wrap{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle9-mobile .uagb-tab{border-radius: 30px;border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle9-mobile > .uagb-tabs__body-wrap{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle10-mobile{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__vstyle10-mobile ul.uagb-tabs__panel .uagb-tab{border-width: 0px;border-style: none;}.uagb-block-185bbe61.uagb-tabs__vstyle10-mobile .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-185bbe61.uagb-tabs__vstyle10-mobile ul.uagb-tabs__panel .uagb-tab.uagb-tabs__active{border-top: 0;border-left: 0;border-bottom: 0;outline: 0;border-radius: 0;border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__stack1-mobile > .uagb-tabs__panel .uagb-tab{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__stack1-mobile > .uagb-tabs__body-wrap{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__stack2-mobile .uagb-tab{border-bottom: 0;outline: 0;border-radius: 0;border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__stack2-mobile > .uagb-tabs__body-wrap{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__stack3-mobile .uagb-tab{border-radius: 30px;border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__stack3-mobile > .uagb-tabs__body-wrap{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__stack4-mobile{border-style: solid;border-color: var(--ast-global-color-6);}.uagb-block-185bbe61.uagb-tabs__stack4-mobile .uagb-tab{border-top-width: 0px;border-right-width: 0px;border-left-width: 0px;border-bottom-width: 0px;border-top: 0;border-left: 0;border-right: 0;border-bottom: 0;outline: 0;border-radius: 0;}.uagb-block-185bbe61.uagb-tabs__stack4-mobile .uagb-tab.uagb-tabs__active{border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: var(--ast-global-color-6);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bc5b94d8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bc5b94d8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-bc5b94d8{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: ;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3aa44ff0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3aa44ff0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3aa44ff0{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-7);;flex-wrap: wrap;}.uagb-block-cfc3a24a .uagb-ifb-desc{margin-bottom: 0px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-cfc3a24a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cfc3a24a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-cfc3a24a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-cfc3a24a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-cfc3a24a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 20px;padding-right: 0px;padding-bottom: 20px;padding-left: 20px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 20px;padding-right: 0px;padding-bottom: 20px;padding-left: 20px;}.uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-cfc3a24a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0424776f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0424776f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-0424776f{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 30px !important;margin-bottom: 60px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-6);;}.wp-block-uagb-container.uagb-block-0424776f::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);mix-blend-mode: normal;background-clip: padding-box;opacity: 1;}.uagb-block-5cfd56e6 .uagb-ifb-desc{margin-bottom: 0px;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-5cfd56e6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5cfd56e6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-5cfd56e6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-5cfd56e6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-5cfd56e6 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-5cfd56e6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-8952eeba .uagb-ifb-desc{margin-bottom: 0px;}.uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-8952eeba .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8952eeba .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8952eeba .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8952eeba .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-8952eeba .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-8952eeba.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 30px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-8952eeba.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 30px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-8952eeba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c43e3f9f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c43e3f9f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c43e3f9f{padding-top: 0px;padding-bottom: 0px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-caa60b3b.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-caa60b3b.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-95d398e8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-95d398e8 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}.uagb-block-9ae6b2ea.uagb-faq-icon-row .uagb-faq-item .uagb-faq-icon-wrap{margin-right: 10px;}.uagb-block-9ae6b2ea .uagb-faq-item{border-style: solid;border-color: #D2D2D2;}.uagb-block-9ae6b2ea.uagb-faq-icon-row-reverse .uagb-faq-item .uagb-faq-icon-wrap{margin-left: 10px;}.uagb-block-9ae6b2ea .uagb-faq-questions-button{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-9ae6b2ea .uagb-faq-content{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-9ae6b2ea .uagb-faq-content span{margin-top: 10px;margin-bottom: 10px;margin-right: 10px;margin-left: 10px;}.uagb-block-9ae6b2ea.uagb-faq__outer-wrap{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.uagb-block-3ddaf554 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3ddaf554 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-3ddaf554 .uagb-ifb-icon svg{fill: #333;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3ddaf554 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3ddaf554 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3ddaf554 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3ddaf554 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3ddaf554 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3ddaf554 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3ddaf554 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-3ddaf554 .uagb-ifb-title{font-size: 24px;color: var(--ast-global-color-0);margin-bottom: 10px;}.uagb-block-3ddaf554 .uagb-ifb-desc{color: var(--ast-global-color-0);margin-bottom: 20px;}.uagb-block-3ddaf554 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-3ddaf554 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-3ddaf554 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-3ddaf554 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3ddaf554 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-3ddaf554.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3ddaf554 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3ddaf554 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3ddaf554 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3ddaf554 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3ddaf554 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ddaf554 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3ddaf554 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ddaf554 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3ddaf554 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3ddaf554 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3ddaf554 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3ddaf554.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-694046dc .uagb-ifb-icon svg{fill: #333;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-694046dc .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-694046dc .uagb-ifb-desc{color: var(--ast-global-color-0);margin-bottom: 20px;}.uagb-block-694046dc .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-694046dc .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-694046dc .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-694046dc .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-infobox__content-wrap{text-align: left;}.uagb-block-694046dc.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-694046dc.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-694046dc .uagb-ifb-icon svg{fill: #333;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-694046dc .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-694046dc .uagb-ifb-desc{color: var(--ast-global-color-0);margin-bottom: 20px;}.uagb-block-694046dc .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-694046dc .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-694046dc .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-694046dc .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-infobox__content-wrap{text-align: left;}.uagb-block-694046dc.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-694046dc.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-advanced-heading.uagb-block-dc4a9001.wp-block-uagb-advanced-heading {margin-bottom: -50px;padding-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-dc4a9001.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-dc4a9001.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-dc4a9001.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-dc4a9001.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.uagb-block-c66cdb91 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c66cdb91 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-c66cdb91 .uagb-ifb-icon svg{fill: #333;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c66cdb91 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c66cdb91 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c66cdb91 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c66cdb91 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c66cdb91 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c66cdb91 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c66cdb91 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-c66cdb91 .uagb-ifb-title{font-family: \"Poppins\";font-size: 24px;color: var(--ast-global-color-0);margin-bottom: 10px;}.uagb-block-c66cdb91 .uagb-ifb-desc{color: var(--ast-global-color-2);margin-bottom: 20px;}.uagb-block-c66cdb91 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-c66cdb91 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-c66cdb91 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-c66cdb91 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c66cdb91 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-c66cdb91.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-c66cdb91 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c66cdb91 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c66cdb91 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-c66cdb91 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-c66cdb91 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c66cdb91 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-c66cdb91 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c66cdb91 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c66cdb91 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c66cdb91 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-c66cdb91 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-c66cdb91.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-694046dc .uagb-ifb-icon svg{fill: #333;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-694046dc .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-694046dc .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-694046dc .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-694046dc .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-694046dc .uagb-ifb-desc{font-family: \"Poppins\";font-size: 16px;color: var(--ast-global-color-2);margin-bottom: 20px;}.uagb-block-694046dc .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-694046dc .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-694046dc .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-694046dc .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-infobox__content-wrap{text-align: left;}.uagb-block-694046dc.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-694046dc.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-694046dc .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-694046dc .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-694046dc.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-block-5ae6b4a9.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-5ae6b4a9.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-5ea173fd.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-5ea173fd.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-button__link{text-transform: normal;text-decoration: none;}@media only screen and (max-width: 976px) {.uagb-block-5ae6b4a9.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-5ae6b4a9.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-5ea173fd.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}@media only screen and (max-width: 767px) {.uagb-block-5ae6b4a9.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-5ae6b4a9.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-5ea173fd.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-5ea173fd .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all .2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;line-height: em;color: var(--ast-global-color-3);}.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .wp-block-uagb-icon-list-child{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-272e24a2.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 5px;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-591e8179.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #63637a !important;color: #63637a !important;}.uagb-block-591e8179.wp-block-uagb-icon-list-child .uagb-icon-list__label{color: var(--ast-global-color-3) !important;}.uagb-block-591e8179.wp-block-uagb-icon-list-child:hover .uagb-icon-list__label{color: var(--ast-global-color-3) !important;}.uagb-block-591e8179.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-591e8179.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-8efe3fd9.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #63637a !important;color: #63637a !important;}.uagb-block-8efe3fd9.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-8efe3fd9.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-eef5eca3.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #63637a !important;color: #63637a !important;}.uagb-block-eef5eca3.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-eef5eca3.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-ff10b1f9.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #63637a !important;color: #63637a !important;}.uagb-block-ff10b1f9.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-ff10b1f9.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-94b38bed.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #63637a !important;color: #63637a !important;}.uagb-block-94b38bed.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-94b38bed.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-272e24a2.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 5px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__label{text-align: center;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-272e24a2 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;margin-top: -30px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-icon-list.uagb-block-272e24a2.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 5px;}}.uagb-block-5eb4bbe8.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-5eb4bbe8.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-5eb4bbe8 .uagb-buttons-repeater:not(.wp-block-button__link){font-weight: 400;font-size: 16px;}.uagb-block-5eb4bbe8 .uagb-button__wrapper .uagb-buttons-repeater.wp-block-button__link{font-weight: 400;font-size: 16px;}.uagb-block-5eb4bbe8 .uagb-button__wrapper .uagb-buttons-repeater.ast-outline-button{font-weight: 400;font-size: 16px;}.uagb-block-5eb4bbe8 .uagb-button__wrapper{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .wp-block-button__link:hover{background: #63637a;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .wp-block-button__link:focus{background: #63637a;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 18px;padding-bottom: 15px;padding-left: 70px;padding-right: 70px;margin-top: -20px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: -20px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-b4dc9b13.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-b4dc9b13.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-button__link{text-transform: normal;text-decoration: none;}@media only screen and (max-width: 976px) {.uagb-block-5eb4bbe8.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-5eb4bbe8.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-b4dc9b13.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}@media only screen and (max-width: 767px) {.uagb-block-5eb4bbe8.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-5eb4bbe8.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-b4dc9b13.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-b4dc9b13 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}\";s:2:\"js\";s:613:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBTabs.init( '.uagb-block-185bbe61' );\n\tUAGBTabs.anchorTabId( '.uagb-block-185bbe61' );\n});\nwindow.addEventListener( 'hashchange', function() {\n\tUAGBTabs.anchorTabId( '.uagb-block-185bbe61' );\n}, false );\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-95d398e8' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-5ea173fd' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-b4dc9b13' );\n});\n });\";s:18:\"current_block_list\";a:22:{i:0;s:14:\"uagb\/container\";i:2;s:21:\"uagb\/advanced-heading\";i:4;s:14:\"core\/paragraph\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:9:\"uagb\/tabs\";i:8;s:15:\"uagb\/tabs-child\";i:11;s:13:\"uagb\/info-box\";i:13;s:14:\"core\/shortcode\";i:14;s:12:\"uagb\/buttons\";i:15;s:18:\"uagb\/buttons-child\";i:16;s:8:\"uagb\/faq\";i:17;s:14:\"uagb\/faq-child\";i:18;s:11:\"core\/search\";i:19;s:10:\"core\/group\";i:20;s:12:\"core\/heading\";i:21;s:17:\"core\/latest-posts\";i:22;s:20:\"core\/latest-comments\";i:23;s:13:\"core\/archives\";i:24;s:15:\"core\/categories\";i:25;s:14:\"uagb\/icon-list\";i:26;s:20:\"uagb\/icon-list-child\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1783166229\";s:6:\"gfonts\";a:1:{s:7:\"Poppins\";a:2:{s:10:\"fontfamily\";s:7:\"Poppins\";s:12:\"fontvariants\";a:3:{i:0;s:3:\"500\";i:1;s:3:\"600\";i:2;s:3:\"400\";}}}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:1;}"]},"uagb_featured_image_src":{"full":["https:\/\/drmaslauskas.com\/wp-content\/uploads\/2025\/03\/krutu-didinimas.jpg",1024,576,false],"thumbnail":["https:\/\/drmaslauskas.com\/wp-content\/uploads\/2025\/03\/krutu-didinimas-150x150.jpg",150,150,true],"medium":["https:\/\/drmaslauskas.com\/wp-content\/uploads\/2025\/03\/krutu-didinimas-300x169.jpg",300,169,true],"medium_large":["https:\/\/drmaslauskas.com\/wp-content\/uploads\/2025\/03\/krutu-didinimas-768x432.jpg",768,432,true],"large":["https:\/\/drmaslauskas.com\/wp-content\/uploads\/2025\/03\/krutu-didinimas.jpg",1024,576,false],"1536x1536":["https:\/\/drmaslauskas.com\/wp-content\/uploads\/2025\/03\/krutu-didinimas.jpg",1024,576,false],"2048x2048":["https:\/\/drmaslauskas.com\/wp-content\/uploads\/2025\/03\/krutu-didinimas.jpg",1024,576,false]},"uagb_author_info":{"display_name":"JoAst-1","author_link":"https:\/\/drmaslauskas.com\/en\/author\/joast-1\/"},"uagb_comment_info":0,"uagb_excerpt":"Breast implant surgery Breast implant surgery Breast implant surgery is an aesthetic surgery procedure that remains one of the most popular worldwide. Breasts have always been considered one of the symbols of femininity, and thanks to modern medicine it is even easier to achieve the desired look, get rid of complexes and enjoy greater self-confidence.&hellip;","_links":{"self":[{"href":"https:\/\/drmaslauskas.com\/en\/wp-json\/wp\/v2\/pages\/5333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drmaslauskas.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/drmaslauskas.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/drmaslauskas.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/drmaslauskas.com\/en\/wp-json\/wp\/v2\/comments?post=5333"}],"version-history":[{"count":4,"href":"https:\/\/drmaslauskas.com\/en\/wp-json\/wp\/v2\/pages\/5333\/revisions"}],"predecessor-version":[{"id":5409,"href":"https:\/\/drmaslauskas.com\/en\/wp-json\/wp\/v2\/pages\/5333\/revisions\/5409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drmaslauskas.com\/en\/wp-json\/wp\/v2\/media\/5593"}],"wp:attachment":[{"href":"https:\/\/drmaslauskas.com\/en\/wp-json\/wp\/v2\/media?parent=5333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}